{"id":129637,"date":"2025-01-02T19:28:00","date_gmt":"2025-01-02T19:28:00","guid":{"rendered":"https:\/\/smilingway.cz\/lago-di-como-2023-sehenswuerdigkeiten-reisefuehrer-und-nuetzliche-tipps\/"},"modified":"2025-12-12T04:58:41","modified_gmt":"2025-12-12T04:58:41","slug":"lago-di-como-italien","status":"publish","type":"post","link":"https:\/\/smilingway.cz\/de\/lago-di-como-italien\/","title":{"rendered":"Lago di Como 2026: Sehensw\u00fcrdigkeiten, Reisef\u00fchrer und n\u00fctzliche Tipps"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Der Lago di Como ist einer der sch\u00f6nsten Seen<a href=\"https:\/\/smilingway.cz\/de\/reiseziele-in-italien\/\" target=\"_blank\" rel=\"noreferrer noopener\"> Italiens.<\/a> Ber\u00fchmtheiten wie George Clooney, Giovanni Versace, Lionel Messi und Madonna haben sich hier niedergelassen. Der komplette Reisef\u00fchrer hilft Ihnen bei der Planung Ihres Urlaubs, mit allem, was Sie wissen m\u00fcssen &#8211; was es am Comer See zu sehen gibt, Schwimmen, Wandern, Transport, Bootsfahrten auf dem Comer See, Unterk\u00fcnfte und andere n\u00fctzliche Informationen und Tipps.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ich habe den <strong>Lago di Como<\/strong> erst vor ein paar Jahren entdeckt. Ich war auf der Suche nach Tipps f\u00fcr interessante Orte in der Umgebung von <a href=\"https:\/\/smilingway.cz\/de\/mailand\/\" target=\"_blank\" rel=\"noreferrer noopener\">Mailand<\/a>. Onkel Google riet zum Comer See und ich muss zugeben, dass er perfekt beraten hat.  <\/p>\n\n\n\t\t\t\t<div class=\"wp-block-uagb-table-of-contents uagb-toc__align-left uagb-toc__columns-1 uagb-toc__collapse uagb-block-be2cc2f9      \"\n\t\t\t\t\tdata-scroll= \"1\"\n\t\t\t\t\tdata-offset= \"30\"\n\t\t\t\t\tstyle=\"\"\n\t\t\t\t>\n\t\t\t\t<div class=\"uagb-toc__wrap\">\n\t\t\t\t\t\t<div class=\"uagb-toc__title\">\n\t\t\t\t\t\t\tInhalt\t\t\t\t\t\t\t\t\t\t\t\t\t<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox= \"0 0 384 512\"><path d=\"M192 384c-8.188 0-16.38-3.125-22.62-9.375l-160-160c-12.5-12.5-12.5-32.75 0-45.25s32.75-12.5 45.25 0L192 306.8l137.4-137.4c12.5-12.5 32.75-12.5 45.25 0s12.5 32.75 0 45.25l-160 160C208.4 380.9 200.2 384 192 384z\"><\/path><\/svg>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uagb-toc__list-wrap \">\n\t\t\t\t\t\t<ol class=\"uagb-toc__list\"><li class=\"uagb-toc__list\"><a href=\"#warum-den-lago-di-como-besuchen\" class=\"uagb-toc-link__trigger\">Warum den Lago di Como besuchen<\/a><li class=\"uagb-toc__list\"><a href=\"#interessante-punkte-\u00fcber-den-lago-di-como\" class=\"uagb-toc-link__trigger\">Interessante Punkte \u00fcber den Lago di Como<\/a><li class=\"uagb-toc__list\"><a href=\"#reiseziele-und-sehensw\u00fcrdigkeiten-in-der-n\u00e4he-des-lago-di-como\" class=\"uagb-toc-link__trigger\">Reiseziele und Sehensw\u00fcrdigkeiten in der N\u00e4he des Lago di Como<\/a><ul class=\"uagb-toc__list\"><li class=\"uagb-toc__list\"><a href=\"#bellagio-der-sch\u00f6nste-ort-am-lago-di-como\" class=\"uagb-toc-link__trigger\">Bellagio &#8211; der sch\u00f6nste Ort am Lago di Como<\/a><li class=\"uagb-toc__list\"><li class=\"uagb-toc__list\"><a href=\"#varenna-ein-muss-f\u00fcr-jeden-besucher-am-lago-di-como\" class=\"uagb-toc-link__trigger\">Varenna &#8211; ein Muss f\u00fcr jeden Besucher am Lago di Como<\/a><li class=\"uagb-toc__list\"><li class=\"uagb-toc__list\"><a href=\"#como-der-gr\u00f6\u00dfte-ferienort-am-see-mit-einer-pr\u00e4chtigen-kathedrale\" class=\"uagb-toc-link__trigger\">Como &#8211; der gr\u00f6\u00dfte Ferienort am See mit einer pr\u00e4chtigen Kathedrale<\/a><li class=\"uagb-toc__list\"><li class=\"uagb-toc__list\"><a href=\"#bootfahren-auf-dem-see\" class=\"uagb-toc-link__trigger\">Bootfahren auf dem See<\/a><li class=\"uagb-toc__list\"><li class=\"uagb-toc__list\"><a href=\"#villa-balbianello\" class=\"uagb-toc-link__trigger\">Villa Balbianello<\/a><\/li><\/ul><\/li><li class=\"uagb-toc__list\"><a href=\"#baden-und-str\u00e4nde-am-lago-di-como\" class=\"uagb-toc-link__trigger\">Baden und Str\u00e4nde am Lago di Como<\/a><ul class=\"uagb-toc__list\"><li class=\"uagb-toc__list\"><a href=\"#str\u00e4nde-am-lago-di-como-karte\" class=\"uagb-toc-link__trigger\">Str\u00e4nde am Lago di Como + Karte<\/a><\/li><\/ul><\/li><\/ul><\/li><li class=\"uagb-toc__list\"><a href=\"#wandern-rund-um-den-lago-di-como\" class=\"uagb-toc-link__trigger\">Wandern rund um den Lago di Como<\/a><ul class=\"uagb-toc__list\"><li class=\"uagb-toc__list\"><a href=\"#besteigung-des-monte-legnone\" class=\"uagb-toc-link__trigger\">Besteigung des Monte Legnone<\/a><li class=\"uagb-toc__list\"><li class=\"uagb-toc__list\"><a href=\"#besteigung-des-monte-bregnano\" class=\"uagb-toc-link__trigger\">Besteigung des Monte Bregnano<\/a><li class=\"uagb-toc__list\"><li class=\"uagb-toc__list\"><a href=\"#aufstieg-zum-monte-grona\" class=\"uagb-toc-link__trigger\">Aufstieg zum Monte Grona<\/a><li class=\"uagb-toc__list\"><li class=\"uagb-toc__list\"><a href=\"#besteigung-des-monte-palanzone\" class=\"uagb-toc-link__trigger\">Besteigung des Monte Palanzone<\/a><li class=\"uagb-toc__list\"><li class=\"uagb-toc__list\"><a href=\"#besteigung-des-monte-san-primo\" class=\"uagb-toc-link__trigger\">Besteigung des Monte San Primo<\/a><li class=\"uagb-toc__list\"><li class=\"uagb-toc__list\"><a href=\"#aufstieg-zum-bergmassiv-der-grigna\" class=\"uagb-toc-link__trigger\">Aufstieg zum Bergmassiv der Grigna<\/a><\/li><\/ul><\/li><\/ul><\/li><\/ul><\/li><li class=\"uagb-toc__list\"><a href=\"#unterk\u00fcnfte-in-der-n\u00e4he-des-lago-di-como\" class=\"uagb-toc-link__trigger\">Unterk\u00fcnfte in der N\u00e4he des Lago di Como<\/a><li class=\"uagb-toc__list\"><a href=\"#wie-man-zum-comer-see-kommt\" class=\"uagb-toc-link__trigger\">Wie man zum Comer See kommt<\/a><ul class=\"uagb-toc__list\"><li class=\"uagb-toc__list\"><a href=\"#mit-dem-flugzeug-zum-lago-di-como\" class=\"uagb-toc-link__trigger\">Mit dem Flugzeug zum Lago di Como<\/a><li class=\"uagb-toc__list\"><li class=\"uagb-toc__list\"><a href=\"#mit-dem-auto-zum-lago-di-como\" class=\"uagb-toc-link__trigger\">Mit dem Auto zum Lago di Como<\/a><\/li><\/ul><\/li><\/ul><\/li><\/ul><\/li><\/ul><\/li><li class=\"uagb-toc__list\"><a href=\"#transport-am-lago-di-como\" class=\"uagb-toc-link__trigger\">Transport am Lago di Como<\/a><li class=\"uagb-toc__list\"><a href=\"#wetter-am-comer-see\" class=\"uagb-toc-link__trigger\">Wetter am Comer See<\/a><li class=\"uagb-toc__list\"><a href=\"#preise-am-comer-see\" class=\"uagb-toc-link__trigger\">Preise am Comer See<\/a><li class=\"uagb-toc__list\"><a href=\"#praktische-informationen-vor-der-reise-an-den-lago-di-como\" class=\"uagb-toc-link__trigger\">Praktische Informationen vor der Reise an den Lago di Como<\/a><li class=\"uagb-toc__list\"><a href=\"#die-besten-buchungsm\u00f6glichkeiten-f\u00fcr-den-besuch-des-lago-di-como\" class=\"uagb-toc-link__trigger\">Die besten Buchungsm\u00f6glichkeiten f\u00fcr den Besuch des Lago di Como<\/a><li class=\"uagb-toc__list\"><a href=\"#mehr-informationen-\u00fcber-italien\" class=\"uagb-toc-link__trigger\">Mehr Informationen \u00fcber Italien<\/a><li class=\"uagb-toc__list\"><a href=\"#zusammenfassung-lago-di-como\" class=\"uagb-toc-link__trigger\">Zusammenfassung: Lago di Como<\/a><\/ul><\/ul><\/ul><\/ul><\/ol>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"proc-navstivit-lago-di-como\">Warum den Lago di Como besuchen<\/h2>\n\n\n\n<p class=\"has-very-dark-gray-color has-text-color wp-block-paragraph\"><strong>Der Comer See<\/strong>, das ist ein einziger gro\u00dfer Kitsch. Malerische St\u00e4dte mit engen Gassen, bunten H\u00e4usern an der K\u00fcste und klarem Wasser, in dem sich die schneebedeckten Gipfel der Alpen spiegeln. Nicht umsonst ist er einer der sch\u00f6nsten italienischen Seen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der Lago di Como bietet eine F\u00fclle von Aktivit\u00e4ten. Sie k\u00f6nnen sich am Wasser bei einem leckeren italienischen Gelato entspannen, abends an der Promenade flanieren, eine F\u00e4hrfahrt zu den umliegenden St\u00e4dten unternehmen oder auf einen der Gipfel wandern, wo Sie den Comer See in der Hand haben.  <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_132351.jpg\"><img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_132351.jpg\" alt=\"Blick auf Bellagio von der F\u00e4hre aus \/ Lago di Como \/ Sehenswertes am Lago di Como\" class=\"wp-image-122022\" srcset=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_132351.jpg 1024w, https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_132351-300x225.jpg 300w, https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_132351-768x576.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\"><em>Blick auf Bellagio von der F\u00e4hre aus<\/em><\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"nekolik-faktu-o-lago-di-como\">Interessante Punkte \u00fcber den Lago di Como<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Die Form des Sees \u00e4hnelt einem umgekehrten Y. Am linken Ende befindet sich die gr\u00f6\u00dfte Stadt am See &#8211; Como &#8211; und am rechten Ende liegt die Stadt Lecco.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der Comer See hat eine Fl\u00e4che von 146 km\u00b2, eine L\u00e4nge von 51 km und eine Breite von 4,5 km. Damit ist er nach dem <a href=\"https:\/\/smilingway.cz\/lago-di-garda-italie\/\" target=\"_blank\" rel=\"noreferrer noopener\">Gardasee<\/a> und dem Lago di Maggiore der drittgr\u00f6\u00dfte See in <a href=\"https:\/\/smilingway.cz\/severni-italie\/\" target=\"_blank\" rel=\"noreferrer noopener\">Norditalien<\/a>. Mit einer Tiefe von 410 m unter dem Meeresspiegel ist er der f\u00fcnfttiefste See in Europa. Die ersten vier Pl\u00e4tze werden von norwegischen Seen belegt.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Im See liegt die 146 km\u00b2 gro\u00dfe Insel Isola Comacina, auf der sich die lombardischen K\u00f6nige vor den Invasoren versteckten.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_135239.jpg\"><img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_135239.jpg\" alt=\"Blick auf den Lago di Como von Bellagio aus \/ Lago di Como F\u00fchrer\" class=\"wp-image-122028\" srcset=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_135239.jpg 1024w, https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_135239-300x225.jpg 300w, https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_135239-768x576.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\"><em>Blick auf den Lago di Como von Bellagio aus<\/em><\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"co-navstivit-u-lago-di-como\">Reiseziele und Sehensw\u00fcrdigkeiten in der N\u00e4he des Lago di Como<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Hier ist es klar &#8211; zu den sch\u00f6nsten Orten geh\u00f6ren die Ferienorte Varenna und Bellagio im zentralen Teil des Sees. Die beiden Orte sind durch eine F\u00e4hre miteinander verbunden und die Fahrt zwischen ihnen dauert etwa eine Viertelstunde.  <\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"bellagio-nejkrasnejsi-letovisko-na-lago-di-como\">Bellagio &#8211; der sch\u00f6nste Ort am Lago di Como<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Die Perle der Insel, so sagen viele, ist die Stadt <strong>Bellagio<\/strong>. Das liegt vor allem an seiner idealen Lage, dank derer man den See von allen Seiten genie\u00dfen kann.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bellagio ist gepr\u00e4gt von steilen und engen Gassen mit kleinen Gesch\u00e4ften und Caf\u00e9s. Sie k\u00f6nnen auch einen Spaziergang entlang der \u00f6rtlichen Strandpromenade machen, von wo aus Sie eine sch\u00f6ne Aussicht genie\u00dfen k\u00f6nnen. Wenn Sie sich f\u00fcr Geschichte interessieren, besuchen Sie die romanische Basilika St. Jakobus und die Kirche St. George.  <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_133509.jpg\"><img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_133509.jpg\" alt=\"Sehenswertes in Norditalien \/ Lombardei Comer See \/ Bellagio-Promenade\" class=\"wp-image-122048\" srcset=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_133509.jpg 1024w, https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_133509-300x225.jpg 300w, https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_133509-768x576.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\"><em>Promenade in Bellagio<\/em><\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_141612.jpg\"><img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_141612.jpg\" alt=\"Bellagio \/ Freizeitaktivit\u00e4ten in der N\u00e4he des Lago di Como\" class=\"wp-image-122053\" srcset=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_141612.jpg 1024w, https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_141612-300x225.jpg 300w, https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_141612-768x576.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\"><em>Bellagio \/ Freizeitaktivit\u00e4ten in der N\u00e4he des Lago di Como<\/em><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Bellagio ist zweifelsohne ein wundersch\u00f6ner Ort. Aber so sch\u00f6n sie auch ist, sie ist \u00fcberf\u00fcllt. Im Sommer bereitet sie buchst\u00e4blich Kopfschmerzen, was durch die engen Stra\u00dfen noch verst\u00e4rkt wird.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die beste Zeit f\u00fcr einen Besuch ist der Winter oder der Sp\u00e4therbst und der fr\u00fche Fr\u00fchling. Andererseits k\u00f6nnen einige Gesch\u00e4fte und Restaurants w\u00e4hrend dieser Zeit geschlossen sein.  <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_141637.jpg\"><img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_141637.jpg\" alt=\"Bellagio \/ Freizeitaktivit\u00e4ten in der N\u00e4he des Lago di Como\" class=\"wp-image-122058\" srcset=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_141637.jpg 1024w, https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_141637-300x225.jpg 300w, https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_141637-768x576.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\"><em>Bellagio \/ Freizeitaktivit\u00e4ten in der N\u00e4he des Lago di Como<\/em><\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"varenna-letovisko-ktere-musite-na-lago-di-como-navstivit\">Varenna &#8211; ein Muss f\u00fcr jeden Besucher am Lago di Como<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Varenna<\/strong> ist ein Ferienort am Ostufer des Sees. Man nennt sie die <em>Stadt der tausend M\u00f6glichkeiten und der tausend Gr\u00fcnde f\u00fcr einen Besuch<\/em><strong>.<\/strong> Ich selbst muss sagen, dass ich von dieser Stadt begeistert bin.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Was ich in Bellagio vermisst habe, habe ich in Varenna gefunden. Frieden und Ruhe strahlten aus jeder Ecke. Dazu kommen die sch\u00f6nen bunten H\u00e4user, die die K\u00fcste s\u00e4umen.  <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_105205.jpg\"><img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_105205.jpg\" alt=\"Varenna Lago di Como\" class=\"wp-image-122063\" srcset=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_105205.jpg 1024w, https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_105205-300x225.jpg 300w, https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_105205-768x576.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\"><em>Varenna Lago di Como<\/em><\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_105406.jpg\"><img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_105406.jpg\" alt=\"Varenna Lago di Como\" class=\"wp-image-122068\" srcset=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_105406.jpg 1024w, https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_105406-300x225.jpg 300w, https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_105406-768x576.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\"><em>Varenna Lago di Como<\/em><\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_113409.jpg\"><img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_113409.jpg\" alt=\"Varenna Lago di Como\" class=\"wp-image-122073\" srcset=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_113409.jpg 1024w, https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_113409-300x225.jpg 300w, https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_113409-768x576.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\"><em>Varenna Lago di Como<\/em><\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_113600.jpg\"><img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_113600.jpg\" alt=\"Varenna Lago di Como\" class=\"wp-image-122078\" srcset=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_113600.jpg 1024w, https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_113600-300x225.jpg 300w, https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_113600-768x576.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\"><em>Varenna Lago di Como<\/em><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Sch\u00f6ne G\u00e4rten finden Sie in den Villen <a aria-label=\"Monastero (otev\u0159e se na nov\u00e9 z\u00e1lo\u017ece)\" href=\"https:\/\/www.google.com\/maps\/place\/Villa+Monastero\/@46.0090851,9.2826081,17z\/data=!3m1!4b1!4m5!3m4!1s0x47841d292e95ed19:0x51df2f1432d7bff3!8m2!3d46.0090814!4d9.2847968\" target=\"_blank\" rel=\"noreferrer noopener\">Monastero<\/a> und <a aria-label=\"Cipresi (otev\u0159e se na nov\u00e9 z\u00e1lo\u017ece)\" href=\"https:\/\/www.google.com\/maps\/place\/Hotel+Villa+Cipressi\/@46.0093094,9.2825032,17z\/data=!3m1!4b1!4m5!3m4!1s0x4780d641fdc5af67:0x8f4fbc567166a26d!8m2!3d46.0093057!4d9.2846919\" target=\"_blank\" rel=\"noreferrer noopener\">Cipresi<\/a>. Ein weiteres St\u00fcck Geschichte findet sich oberhalb der Stadt auf einem 150 m hohen Felsvorsprung, wo die <a aria-label=\"z\u0159\u00edcenina hradu Vezio (otev\u0159e se na nov\u00e9 z\u00e1lo\u017ece)\" href=\"https:\/\/www.google.com\/maps\/place\/23828+Vezio,+Provincie+Lecco,+It%C3%A1lie\/@46.0105802,9.2878721,17z\/data=!3m1!4b1!4m5!3m4!1s0x478417c78e22af25:0x260678033eb217b1!8m2!3d46.0100936!4d9.2896758\" target=\"_blank\" rel=\"noreferrer noopener\">Ruinen der Burg Vezio<\/a> stehen. F\u00fcr den Aufstieg ben\u00f6tigen Sie etwa 1,5 Stunden.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In Varenna finden Sie den k\u00fcrzesten Fluss Italiens &#8211; die Finmelatte, die nur 250 Meter lang ist. Man kann ihn nur von M\u00e4rz bis Oktober sehen. Er ist so kurz, dass Sie ihn nicht einmal auf Google Maps finden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fahren Sie mit dem Zug nach Varenna? Von Lecco aus f\u00e4hrt der Zug in regelm\u00e4\u00dfigen Abst\u00e4nden, mindestens einmal pro Stunde. Das Ticket kostet 3 \u20ac. Sie steigen am Bahnhof Varenna-Esino aus, von wo aus Sie einfach den H\u00fcgel hinunter ins Stadtzentrum laufen.  <\/p>\n\n\n\n<p class=\"has-text-align-center has-ast-global-color-6-background-color has-background wp-block-paragraph\">Lesen: <a href=\"https:\/\/smilingway.cz\/lago-di-garda-italie\/\" target=\"_blank\" rel=\"noreferrer noopener\">Die Sch\u00f6nsten Ausflugsziele am Gardasee<\/a>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"como-nejvetsi-stredisko-u-jezera-s-nadhernou-katedralou\">Como &#8211; der gr\u00f6\u00dfte Ferienort am See mit einer pr\u00e4chtigen Kathedrale<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">In <strong>Como <\/strong>werden Sie alles finden. Str\u00e4nde, Gesch\u00e4fte, Restaurants, Sehensw\u00fcrdigkeiten und Attraktionen. Trotz seiner Lage ganz im S\u00fcden des Sees ist es ein idealer Ausgangspunkt f\u00fcr die Erkundung des Comer Sees.  <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2021\/06\/lake-5462966_1280-1-1024x768.jpg\"><img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2021\/06\/lake-5462966_1280-1-1024x768.jpg\" alt=\"\" class=\"wp-image-25502\" srcset=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2021\/06\/lake-5462966_1280-1-1024x768.jpg 1024w, https:\/\/smilingway.cz\/wp-content\/uploads\/2021\/06\/lake-5462966_1280-1-300x225.jpg 300w, https:\/\/smilingway.cz\/wp-content\/uploads\/2021\/06\/lake-5462966_1280-1-768x576.jpg 768w, https:\/\/smilingway.cz\/wp-content\/uploads\/2021\/06\/lake-5462966_1280-1.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Von Como aus kann man mit der F\u00e4hre in andere St\u00e4dte am Seeufer fahren. In der Umgebung gibt es au\u00dferdem eine Reihe von Wanderwegen, von denen aus man einen herrlichen Blick auf den See und die umliegenden Alpen genie\u00dfen kann.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Oder Sie fahren mit der Seilbahn zum Ort Brunate, der hoch \u00fcber Como liegt und eine fantastische Aussicht bietet.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como wird von der pr\u00e4chtigen Renaissance-Kathedrale Santa Maria Assunta oder Duomo di Como dominiert. Nur einen kurzen Spaziergang entfernt befindet sich das Arch\u00e4ologische Museum, in dem Artefakte und Funde aus dem antiken Griechenland ausgestellt sind, die in der Gegend gefunden wurden.  <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2022\/08\/como-duomo.jpg\"><img decoding=\"async\" width=\"1024\" height=\"640\" src=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2022\/08\/como-duomo.jpg\" alt=\"\" class=\"wp-image-98117\" srcset=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2022\/08\/como-duomo.jpg 1024w, https:\/\/smilingway.cz\/wp-content\/uploads\/2022\/08\/como-duomo-300x188.jpg 300w, https:\/\/smilingway.cz\/wp-content\/uploads\/2022\/08\/como-duomo-768x480.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\"><em>Der Dom von Como<\/em><\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"plavba-lodi-po-jezere\">Bootfahren auf dem See<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Bei einer Bootsfahrt haben Sie einen anderen Blick auf den See, die St\u00e4dte an seinen Ufern und die Gipfel der Alpen. Ein atemberaubender Anblick, den man erleben m\u00f6chte.  <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_130640.jpg\"><img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_130640.jpg\" alt=\"Blick von der F\u00e4hre nach Menaggio \/ Ausflugsziele am Lago di Como\" class=\"wp-image-122090\" srcset=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_130640.jpg 1024w, https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_130640-300x225.jpg 300w, https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_130640-768x576.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\"><em>Blick von der F\u00e4hre nach Menaggio<\/em><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Die F\u00e4hren fahren das ganze Jahr \u00fcber regelm\u00e4\u00dfig, und die Preise variieren je nach Entfernung. Die beliebte Strecke Varenna &#8211; Menaggio &#8211; Bellagio kostet zum Beispiel 4,60 \u20ac. Die Preise f\u00fcr die F\u00e4hren finden Sie auf der<a href=\"http:\/\/www.navigazionelaghi.it\/doc\/pdf\/biglietti\/como\/Tariffe%20viaggiatori.pdf\" target=\"_blank\" rel=\"noreferrer noopener\"> offiziellen Website der Lago di Como F\u00e4hren<\/a>. Sie kaufen Ihr Ticket direkt an der Anlegestelle.  <\/p>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-e064fb7f alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-ac921c3b\"><h4 class=\"uagb-heading-text\">Unterkunft Lago di Como \ud83d\ude34<\/h4><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-11065b68 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-12fadca9\">\n<div class=\"wp-block-uagb-info-box uagb-block-6bde0589 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top uagb-infobox_cta-type-all\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-image-content\"><img decoding=\"async\" src=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/02\/ubytovani-lago-di-como.jpeg\" alt=\"ubytov\u00e1n\u00ed lago di como\" width=\"700\" height=\"400\" loading=\"lazy\"\/><\/div><div class=\"uagb-ifb-title-wrap\"><h5 class=\"uagb-ifb-title\">Hotel Abbadia<\/h5><\/div><p class=\"uagb-ifb-desc\">Gem\u00fctliches Hotel 5 Minuten vom Strand entfernt<\/p><div class=\"uagb-ifb-button-wrapper wp-block-button\"><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-cc259940\">\n<div class=\"wp-block-uagb-info-box uagb-block-3b0ee87a uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top uagb-infobox_cta-type-all\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-image-content\"><img decoding=\"async\" src=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/02\/ubytovani-lago-di-como-2.jpeg\" alt=\"ubytov\u00e1n\u00ed lago di como\" width=\"700\" height=\"400\" loading=\"lazy\"\/><\/div><div class=\"uagb-ifb-title-wrap\"><h5 class=\"uagb-ifb-title\">Wohnsitz Alessandra<\/h5><\/div><p class=\"uagb-ifb-desc\">Wohnungen mit Schwimmbad im Nordwesten des Sees<\/p><div class=\"uagb-ifb-button-wrapper wp-block-button\"><\/div><\/div><\/div>\n<\/div>\n<\/div><\/div>\n<\/div>\n\n\n\n<div style=\"height:29px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"villa-balbianello\">Villa Balbianello<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Die Villa Balbianello befindet sich auf einer Landzunge, die in der N\u00e4he von Lenno in den See ragt. Es handelt sich um einen barocken Villenkomplex aus dem 18. Jahrhundert. Jahrhundert, von dessen Terrassen aus man das gegen\u00fcberliegende Ufer und die St\u00e4dte Vergonese und Bellagio sehen kann.  <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/Villa-Balbianello-2.jpg\"><img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/Villa-Balbianello-2.jpg\" alt=\"Villa Balbianello Lago di Como\" class=\"wp-image-122101\" srcset=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/Villa-Balbianello-2.jpg 1024w, https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/Villa-Balbianello-2-300x225.jpg 300w, https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/Villa-Balbianello-2-768x576.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\"><em>Villa Balbianello<\/em><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Viele bekannte Filme wie Casino Royale und Star Wars: Episode II &#8211; Angriff der Klone wurden hier gedreht. Man erreicht sie \u00fcber die Bucht von Lenno am Westufer des Sees.  <\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"koupani-a-plaze-u-lago-di-como\">Baden und Str\u00e4nde am Lago di Como<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Der <strong>Lago di Como<\/strong> ist ein Alpensee. Und die Kombination aus Alpen und Schwimmen klingt zugegebenerma\u00dfen nicht sehr verlockend. Der Comer See geh\u00f6rt jedoch zu den sogenannten. Warme Alpenseen, in denen man ohne Probleme schwimmen kann.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Wassertemperatur liegt hier im Sommer bei angenehmen 23-25 Grad. Im Fr\u00fchling liegen die Temperaturen zwischen 18 und 22 Grad. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2021\/06\/lake-como-1656394_1280-1-1024x777.jpg\"><img decoding=\"async\" width=\"1024\" height=\"777\" src=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2021\/06\/lake-como-1656394_1280-1-1024x777.jpg\" alt=\"\" class=\"wp-image-25524\" srcset=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2021\/06\/lake-como-1656394_1280-1-1024x777.jpg 1024w, https:\/\/smilingway.cz\/wp-content\/uploads\/2021\/06\/lake-como-1656394_1280-1-300x228.jpg 300w, https:\/\/smilingway.cz\/wp-content\/uploads\/2021\/06\/lake-como-1656394_1280-1-768x583.jpg 768w, https:\/\/smilingway.cz\/wp-content\/uploads\/2021\/06\/lake-como-1656394_1280-1.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center\" id=\"prehled-plazi-u-lago-di-como-mapa\">Str\u00e4nde am Lago di Como + Karte<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Planen Sie, die meiste Zeit Ihres Urlaubs am Wasser zu verbringen? Nicht alle Orte rund um den See sind zum Baden geeignet, daher ist es gut, die Unterkunft strategisch zu w\u00e4hlen.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Strandgebiete k\u00f6nnen in <strong>3 geografische Bereiche<\/strong> unterteilt werden:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>s\u00fcdwestliches Gebiet um die Stadt Como<\/li>\n\n\n\n<li>s\u00fcd\u00f6stliches Gebiet um Lecco<\/li>\n\n\n\n<li>und das n\u00f6rdliche Gebiet um die Stadt Colico<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading has-text-align-center\" id=\"plaze-kolem-mesta-como-jihozapad\">Str\u00e4nde um Como &#8211; S\u00fcdwesten<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Der <strong>Strand von Argegno<\/strong> in der N\u00e4he des kleinen Hafens der Stadt. Vollst\u00e4ndig ausgestatteter Grasstrand mit einer Snackbar. Bezahlte Str\u00e4nde<\/li>\n\n\n\n<li><strong>Sandstrand in Bellagio,<\/strong> wo Sie auch Erfrischungen, Liegest\u00fchle und kostenloses WIFI finden. Bezahlt<\/li>\n\n\n\n<li><strong>Kieselstrand von San Giovanni in Bellagio<\/strong> &#8211; \u00f6ffentlicher Strand mit freiem Eintritt<\/li>\n\n\n\n<li><strong>Offener Grasstrand &#8211; Lido di Villa Geno in Como<\/strong> &#8211; Sie k\u00f6nnen vor Ort einen Sonnenschirm und eine Liege mieten und einen Snack im Restaurant einnehmen. Bezahlt<\/li>\n\n\n\n<li><strong>Lido di Faggeto in der Ortschaft Faggeto Lario<\/strong> &#8211; hat den Vorteil, dass der Eintritt frei ist, ist aber oft \u00fcberf\u00fcllt<\/li>\n\n\n\n<li><strong>Felsenstrand in Griante<\/strong> &#8211; Sie k\u00f6nnen Sonnenschirme, Liegen und Kanus mieten. Kostenlos<\/li>\n\n\n\n<li><strong>Der<\/strong> <strong>Strand von Careno in Nesso<\/strong> besteht halb aus Gras und halb aus Sand. Der Eintritt ist frei.<\/li>\n\n\n\n<li><strong>Pognana Lario ist ein grasbewachsener Strand<\/strong> mit freiem Eintritt, aber der Weg dorthin ist steil und lang.  <\/li>\n\n\n\n<li><strong>Strand in Tremezzina (Lido di Lenno)<\/strong> mit allen Einrichtungen. Abends verwandelt es sich in einen Nachtclub. Bezahlte Str\u00e4nde<\/li>\n\n\n\n<li>Der <strong>grasbewachsene Strand von Lido di Ossuccio befindet sich ebenfalls in Tremezzina<\/strong>, der Eintritt ist frei. Es wird sehr voll.  <\/li>\n\n\n\n<li><strong>In der gleichen Anlage befindet sich auch der Mayer Park<\/strong> mit einem Felsenstrand und einem Volleyballplatz. Bezahlt<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading has-text-align-center\" id=\"plaze-kolem-mesta-lecco-jihovychod\">Str\u00e4nde um Lecco &#8211; S\u00fcdosten<br><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Der<\/strong> <strong>grasbewachsene Strand von Lido di Abbadia (Lecco)<\/strong> mit einem sch\u00f6nen und ruhigen Park und freiem Eintritt.<\/li>\n\n\n\n<li><strong>Der Sandstrand von Lido Orsa Maggiore<\/strong> ist komplett ausgestattet und bietet die M\u00f6glichkeit, Tretboote und Kanus zu mieten. Bezahlt<\/li>\n\n\n\n<li><strong>Sandstrand in Mandello del Lario<\/strong> mit freiem Eintritt. Auch hier k\u00f6nnen Sie Liegest\u00fchle, Sonnenschirme und Erfrischungen nutzen.  <\/li>\n\n\n\n<li><strong>Der Strand von Oliveto Lario<\/strong> mit freiem Eintritt &#8211; ein langer Kieselstrand mit kristallklarem Wasser und umfassenden Einrichtungen.<\/li>\n\n\n\n<li><strong>Der Sandstrand in Perledo (in der N\u00e4he von Varenna)<\/strong> &#8211; wie an den anderen Str\u00e4nden k\u00f6nnen Sie Liegest\u00fchle mieten und einen Snack zu sich nehmen. Bezahlt<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2021\/06\/lecco-2297962_1280-1-1024x682.jpg\"><img decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2021\/06\/lecco-2297962_1280-1-1024x682.jpg\" alt=\"\" class=\"wp-image-25527\" srcset=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2021\/06\/lecco-2297962_1280-1-1024x682.jpg 1024w, https:\/\/smilingway.cz\/wp-content\/uploads\/2021\/06\/lecco-2297962_1280-1-300x200.jpg 300w, https:\/\/smilingway.cz\/wp-content\/uploads\/2021\/06\/lecco-2297962_1280-1-768x512.jpg 768w, https:\/\/smilingway.cz\/wp-content\/uploads\/2021\/06\/lecco-2297962_1280-1.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\"><em>Stadt<\/em> <em>Lecco<\/em><\/figcaption><\/figure>\n\n\n\n<h4 class=\"wp-block-heading has-text-align-center\" id=\"plaze-kolem-mesta-colico-sever\">Str\u00e4nde um Colico &#8211; Norden<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Reisen Sie mit Ihrer Familie?<\/strong> Dann wird der voll ausgestattete <strong>Sandstrand in Bellano<\/strong> ideal sein. Kinder k\u00f6nnen im angrenzenden Schwimmbad planschen. Bezahlte Str\u00e4nde<\/li>\n\n\n\n<li><strong>Lido di Colico in der Ferienanlage Colico<\/strong> mit allen Einrichtungen wie Tennisplatz, Fu\u00dfballplatz und einer Wind- und Kitesurfing-Schule. Sie k\u00f6nnen das Handtuch auf dem Gras oder im Sand ausbreiten. Bezahlte Str\u00e4nde<\/li>\n\n\n\n<li><strong>Ein weiterer Strand in Colico ist der grasbewachsene Strand von Laghetto di Piona<\/strong>. Freier Eintritt und gro\u00dfe schattenspendende B\u00e4ume, was will man mehr :).  <\/li>\n\n\n\n<li><strong>Sand- und Grasstrand von Dervio<\/strong> ohne Einrichtungen.  <\/li>\n\n\n\n<li><strong>Lido di Menaggio<\/strong> &#8211; ein gro\u00dfer Strand mit zwei Schwimmb\u00e4dern, ideal f\u00fcr die ganze Familie. Erfrischungen werden im Restaurant serviert, das Platz f\u00fcr Hunderte von G\u00e4sten bietet. Sie m\u00fcssen sich keine Sorgen machen, dass Sie hungern m\u00fcssen :). Bezahlte Str\u00e4nde<\/li>\n\n\n\n<li><strong>Menaggio hat auch einen Kieselstrand, Lerai <\/strong>, mit freiem Eintritt. Die Serviceleistungen sind hier nicht so umfangreich wie am vorherigen Strand in Menaggio, aber das wird durch die M\u00f6glichkeit, Tretboote, Kanus und Ruderboote zu mieten, ausgeglichen.  <\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_130627.jpg\"><img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_130627.jpg\" alt=\"Menaggio\" class=\"wp-image-122095\" srcset=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_130627.jpg 1024w, https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_130627-300x225.jpg 300w, https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_130627-768x576.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\"><em>Menaggio<\/em><\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"turistika-v-okoli-lago-di-como\">Wandern rund um den Lago di Como<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Bevorzugen Sie einen aktiven Urlaub? Vergessen Sie Ihre Wanderschuhe nicht, denn rund um den Comer See gibt es wunderbare Wanderwege, von denen aus Sie einen herrlichen Blick auf den See und die umliegenden Alpengipfel genie\u00dfen k\u00f6nnen.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">F\u00fcr Anf\u00e4nger sind der <a href=\"https:\/\/mapy.cz\/s\/covepuhopa\" target=\"_blank\" rel=\"noreferrer noopener\">Sentiero del Viandante<\/a>, der sich am Ostufer des Sees entlang windet, oder der <a href=\"https:\/\/mapy.cz\/s\/rakolacepu\" target=\"_blank\" rel=\"noreferrer noopener\">Greenway del Lago di Como<\/a> am Westufer ideal. Beide Routen sind lang, so dass Sie den Beginn der Route je nach Ihrer Unterkunft w\u00e4hlen k\u00f6nnen.  <\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"vystup-na-monte-legnone\">Besteigung des Monte Legnone<\/h3>\n\n\n\n<p class=\"has-very-dark-gray-color has-text-color wp-block-paragraph\">Der <strong>Monte Legnone<\/strong> (2609 m) ist der h\u00f6chste Berg in der Gegend &#8211; der Gipfel liegt 2400 m h\u00f6her als der See. Und das ist eine ganz sch\u00f6ne Steigerung. Der Gipfel ist ein weites Plateau, von dem aus man den Lago di Lugano im Westen und den Piz Bernina im Nordosten der Schweiz sehen kann.  <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2022\/08\/Monte-legnone.jpg\"><img decoding=\"async\" width=\"1024\" height=\"640\" src=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2022\/08\/Monte-legnone.jpg\" alt=\"\" class=\"wp-image-98024\" srcset=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2022\/08\/Monte-legnone.jpg 1024w, https:\/\/smilingway.cz\/wp-content\/uploads\/2022\/08\/Monte-legnone-300x188.jpg 300w, https:\/\/smilingway.cz\/wp-content\/uploads\/2022\/08\/Monte-legnone-768x480.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\"><em>Blick auf den Monte Legnone<\/em><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Die Reise beginnt am Rifugio Roccoli Lorla (1406 m), das man mit dem Auto von Tremenico aus erreicht. Die Stra\u00dfe ist schmal, aber asphaltiert. Unterwegs gibt es kein Wasser zum Auff\u00fcllen, nehmen Sie also ausreichend Wasser mit.  <\/p>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-0a8f7229 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-12d79b7f\"><h4 class=\"uagb-heading-text\">Unterkunft Lago di Como \ud83d\ude34<\/h4><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-5fd08e28 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-7b0f7102\">\n<div class=\"wp-block-uagb-info-box uagb-block-9887ffcd uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top uagb-infobox_cta-type-all\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-image-content\"><img decoding=\"async\" src=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/02\/ubytovani-lago-di-como-3.jpeg\" alt=\"ubytov\u00e1n\u00ed lago di como\" width=\"700\" height=\"400\" loading=\"lazy\"\/><\/div><div class=\"uagb-ifb-title-wrap\"><h5 class=\"uagb-ifb-title\">Hotel Vista Lago<\/h5><\/div><p class=\"uagb-ifb-desc\">Gem\u00fctliches Hotel mit herrlichem Blick <\/p><div class=\"uagb-ifb-button-wrapper wp-block-button\"><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-d14fb2e8\">\n<div class=\"wp-block-uagb-info-box uagb-block-8384c17e uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top uagb-infobox_cta-type-all\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-image-content\"><img decoding=\"async\" src=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/02\/ubytovani-lago-di-como-4.jpeg\" alt=\"ubytov\u00e1n\u00ed lago di como\" width=\"700\" height=\"400\" loading=\"lazy\"\/><\/div><div class=\"uagb-ifb-title-wrap\"><h5 class=\"uagb-ifb-title\">Hotel Il Loggiato Dei Serviti<\/h5><\/div><p class=\"uagb-ifb-desc\">Unterk\u00fcnfte in Como mit hoher Verf\u00fcgbarkeit<\/p><div class=\"uagb-ifb-button-wrapper wp-block-button\"><\/div><\/div><\/div>\n<\/div>\n<\/div><\/div>\n<\/div>\n\n\n\n<div style=\"height:32px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"vystup-na-monte-bregnano\">Besteigung des Monte Bregnano<\/h3>\n\n\n\n<p class=\"has-very-dark-gray-color has-text-color wp-block-paragraph\">Der <strong>Monte Bregagno<\/strong> (2107 m) ist als <em>Balkon \u00fcber dem Lago di Como<\/em> bekannt. Sie k\u00f6nnen zwischen zwei Routen w\u00e4hlen. Der Ausgangspunkt f\u00fcr die erste Route ist der Monte di Breglia oberhalb der Ortschaft Breglia, den man mit dem Auto erreichen kann. Die Reise wird mit einem symbolischen Betrag von 3<strong> <\/strong>\u20ac. Der Automat befindet sich direkt am Anfang der Bergstrecke oberhalb von Breglia. Das Parken auf dem Gipfel ist dann kostenlos.  <\/p>\n\n\n\n<p class=\"has-very-dark-gray-color has-text-color wp-block-paragraph\">Eine Alternative ist, den Bus nach Breglia zu nehmen und von dort aus zum Parkplatz zu laufen (1 Stunde).  <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2021\/06\/lake-como-from-monte-bregagno-4193465_1280-1-1024x768.jpg\"><img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2021\/06\/lake-como-from-monte-bregagno-4193465_1280-1-1024x768.jpg\" alt=\"\" class=\"wp-image-25458\" srcset=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2021\/06\/lake-como-from-monte-bregagno-4193465_1280-1-1024x768.jpg 1024w, https:\/\/smilingway.cz\/wp-content\/uploads\/2021\/06\/lake-como-from-monte-bregagno-4193465_1280-1-300x225.jpg 300w, https:\/\/smilingway.cz\/wp-content\/uploads\/2021\/06\/lake-como-from-monte-bregagno-4193465_1280-1-768x576.jpg 768w, https:\/\/smilingway.cz\/wp-content\/uploads\/2021\/06\/lake-como-from-monte-bregagno-4193465_1280-1.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\"><em>Monte Bregnano<\/em><\/figcaption><\/figure>\n\n\n\n<p class=\"has-very-dark-gray-color has-text-color wp-block-paragraph\">Wir gehen in Richtung Menaggio-H\u00fctte (1383 m) und folgen dem roten Weg an der Kapelle St. Amate vorbei bis zum Gipfel. Die Gesamtzeit f\u00fcr den Auf- und Abstieg betr\u00e4gt etwa 5,5 Stunden ohne Pausen.  <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a aria-label=\"  pl\u00e1nova\u010d trasy na Monte Bregnano (otev\u0159e se na nov\u00e9 z\u00e1lo\u017ece)\" href=\"https:\/\/mapy.cz\/s\/3qxkg\" target=\"_blank\" rel=\"noreferrer noopener\">Route zum Monte Bregnano<\/a><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Die zweite Route ist eher in den Winter- und Fr\u00fchlingsmonaten geeignet, wenn der Weg zum Gipfel noch mit Schnee bedeckt ist. Packen Sie Ihre Winterwanderausr\u00fcstung ein. Lassen Sie das Auto oberhalb der Ortschaft Treccione stehen, wo die Stra\u00dfe in einen Wanderweg \u00fcbergeht.  <\/p>\n\n\n\n<p class=\"has-text-align-center has-ast-global-color-6-background-color has-background wp-block-paragraph\">Lesen: <a href=\"https:\/\/smilingway.cz\/severni-italie\/\" target=\"_blank\" rel=\"noreferrer noopener\">Die sch\u00f6nsten Orte in Norditalien<\/a><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"vystup-na-monte-grona\">Aufstieg zum Monte Grona<\/h3>\n\n\n\n<p class=\"has-very-dark-gray-color has-text-color wp-block-paragraph\">Der <strong>Monte Grona<\/strong> (1736 m) ist ein Gipfel in der N\u00e4he des Monte Bregnano. Der Ausgangspunkt ist wieder die Menaggio-H\u00fctte, die man vom Monte di Breglia aus erreicht, wo es einen gro\u00dfen Parkplatz gibt.  <\/p>\n\n\n\n<p class=\"has-very-dark-gray-color has-text-color wp-block-paragraph\">Die Alternative ist, den Bus nach Breglia zu nehmen und dann auf der Asphaltstra\u00dfe zum Monte di Breglia zu laufen (etwa eine Stunde l\u00e4nger). Vom Monte di Breglia aus kann man den <em>Sentiero Panoramico<\/em> nehmen, einen Panoramaweg mit Blick auf den See und die Umgebung. In 50 Minuten ist man bei der H\u00fctte, die steil in den Felsen eingekeilt ist, und der See ist nur einen Steinwurf entfernt.  <\/p>\n\n\n\n<p class=\"has-very-dark-gray-color has-text-color wp-block-paragraph\">Der Weg zur H\u00fctte dauert weniger als 2 Stunden und ist einfach. Von dort aus k\u00f6nnen Sie weiter zum Monte Grona wandern (je nach gew\u00e4hlter Route etwa 1 Stunde bis zum Gipfel).  <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2022\/08\/monte-grona-1.jpg\"><img decoding=\"async\" width=\"1024\" height=\"640\" src=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2022\/08\/monte-grona-1.jpg\" alt=\"\" class=\"wp-image-98066\" srcset=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2022\/08\/monte-grona-1.jpg 1024w, https:\/\/smilingway.cz\/wp-content\/uploads\/2022\/08\/monte-grona-1-300x188.jpg 300w, https:\/\/smilingway.cz\/wp-content\/uploads\/2022\/08\/monte-grona-1-768x480.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\"><em>Monte Grona<\/em><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">W\u00e4hlen Sie von der H\u00fctte aus eine von 3 Routen &#8211; unterteilt nach Schwierigkeitsgrad + Links zum Herunterladen der Route:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a aria-label=\"v\u00fdstup na Monte Grona p\u0159es Via Normale (otev\u0159e se na nov\u00e9 z\u00e1lo\u017ece)\" href=\"https:\/\/mapy.cz\/s\/3qxkz\" target=\"_blank\" rel=\"noreferrer noopener\">Besteigung des Monte Grona \u00fcber die Via Normale<\/a> &#8211; die einfachste Route f\u00fchrt durch den Bergsattel (Forcoletta), von wo aus man \u00fcber einen steilen Felsenpfad zum Gipfel gelangt.<\/li>\n\n\n\n<li><a aria-label=\"v\u00fdstup na Monte Grona p\u0159es Via Direttissima (otev\u0159e se na nov\u00e9 z\u00e1lo\u017ece)\" href=\"https:\/\/mapy.cz\/s\/3qxkH\" target=\"_blank\" rel=\"noreferrer noopener\">Besteigung des Monte Grona \u00fcber die Via Direttissima<\/a> &#8211; eine m\u00e4\u00dfig schwierige Route, die der S\u00fcdseite des Berges folgt.<\/li>\n\n\n\n<li><a aria-label=\"v\u00fdstup na Monte Grona p\u0159es Via Panoramica (otev\u0159e se na nov\u00e9 z\u00e1lo\u017ece)\" href=\"https:\/\/mapy.cz\/s\/3qxkM\" target=\"_blank\" rel=\"noreferrer noopener\">Aufstieg zum Monte Grona \u00fcber die Via Panoramica<\/a> &#8211; die schwierigste Klettersteigroute; Schwierigkeit EEA -AR-IV-D.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"vystup-na-monte-palanzone\">Besteigung des Monte Palanzone<\/h3>\n\n\n\n<p class=\"has-very-dark-gray-color has-text-color wp-block-paragraph\">Der <strong>Monte Palanzone<\/strong> (1.436 m) ist ein Gipfel zwischen den Ausl\u00e4ufern des Sees. Es gibt mehrere Routen dorthin, von denen die beliebteste in Brunate beginnt. Um hierher zu gelangen, nimmt man die Seilbahn von Como aus und folgt dem roten Wanderweg Dorsale del Triangolo Lariano (Lariano-Dreieck), vorbei an der Kirche Chiesa di Sant Andrea und \u00fcber den Pass.  <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/mapy.cz\/s\/3qxlb\" target=\"_blank\" rel=\"noreferrer noopener\">Route zum Monte Palanzone<\/a><\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2022\/08\/Monte-Palanzone-2.jpg\"><img decoding=\"async\" width=\"1024\" height=\"640\" src=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2022\/08\/Monte-Palanzone-2.jpg\" alt=\"Lago di Como Tourismus\" class=\"wp-image-98055\" srcset=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2022\/08\/Monte-Palanzone-2.jpg 1024w, https:\/\/smilingway.cz\/wp-content\/uploads\/2022\/08\/Monte-Palanzone-2-300x188.jpg 300w, https:\/\/smilingway.cz\/wp-content\/uploads\/2022\/08\/Monte-Palanzone-2-768x480.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\"><em>Route zum Monte Palanzone<\/em><\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"vystup-na-monte-san-primo\">Besteigung des Monte San Primo<\/h3>\n\n\n\n<p class=\"has-very-dark-gray-color has-text-color wp-block-paragraph\">Der <strong>Monte San Primo<\/strong> (1.681 m) befindet sich wie der Monte Palanzone auf dem Larianer Dreieck, nur wenige Kilometer von Bellagio entfernt. Es gibt mehrere Wege dorthin. Der Weg ist ges\u00e4umt von gro\u00dfen Felsbl\u00f6cken ( <em>Pitera Lentina)<\/em>, die durch Gletschererosion entstanden sind.  <\/p>\n\n\n\n<p class=\"has-very-dark-gray-color has-text-color wp-block-paragraph\">Der Zeitaufwand variiert je nach gew\u00e4hlter Route zwischen 4 und 6 Stunden.  <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2022\/08\/monte-san-primo.jpg\"><img decoding=\"async\" width=\"1024\" height=\"640\" src=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2022\/08\/monte-san-primo.jpg\" alt=\"\" class=\"wp-image-98050\" srcset=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2022\/08\/monte-san-primo.jpg 1024w, https:\/\/smilingway.cz\/wp-content\/uploads\/2022\/08\/monte-san-primo-300x188.jpg 300w, https:\/\/smilingway.cz\/wp-content\/uploads\/2022\/08\/monte-san-primo-768x480.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\"><em>Monte San Primo<\/em><\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"vystup-na-horsky-masiv-grigna\">Aufstieg zum Bergmassiv der Grigna<\/h3>\n\n\n\n<p class=\"has-very-dark-gray-color has-text-color wp-block-paragraph\"><strong>Grigna<\/strong> ist ein Bergmassiv, das an die <a href=\"https:\/\/smilingway.cz\/dolomity-nejkrasnejsi-mista\/\" target=\"_blank\" rel=\"noreferrer noopener\">Dolomiten<\/a> erinnert. Es ist einer der eindrucksvollsten Orte am Lago di Como. Seine markanten Gipfel sind die Nord-Grigna (Grigna Settentrionale) mit einer H\u00f6he von 2410 m und die S\u00fcd-Grigna (Grigna Meridionale) mit einer H\u00f6he von 2177 m.  <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2022\/08\/jizni-grigna.jpg\"><img decoding=\"async\" width=\"1024\" height=\"640\" src=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2022\/08\/jizni-grigna.jpg\" alt=\"\" class=\"wp-image-98045\" srcset=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2022\/08\/jizni-grigna.jpg 1024w, https:\/\/smilingway.cz\/wp-content\/uploads\/2022\/08\/jizni-grigna-300x188.jpg 300w, https:\/\/smilingway.cz\/wp-content\/uploads\/2022\/08\/jizni-grigna-768x480.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\"><em>Blick auf den See von S\u00fcd-Grigna aus<\/em><br><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Aufstieg zur S\u00fcdgrigna\/Grignetta<\/strong> &#8211; Ausgangspunkt ist <em>Piani Resinelli<\/em>, das man mit dem Auto oder Bus von Lecco aus erreicht. Der Aufstieg dauert etwa 3 Stunden, aber es gibt auch k\u00fcrzere Routen zu niedrigeren Gipfeln, Bergs\u00e4tteln oder Bergh\u00fctten in der Umgebung.  <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a aria-label=\"trasu na vrchol Ji\u017en\u00ed Grigna (otev\u0159e se na nov\u00e9 z\u00e1lo\u017ece)\" href=\"https:\/\/mapy.cz\/s\/3qzbF\" target=\"_blank\" rel=\"noreferrer noopener\">Route zum Gipfel von South Grigna<\/a><\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2022\/08\/grignetta.jpg\"><img decoding=\"async\" width=\"1024\" height=\"640\" src=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2022\/08\/grignetta.jpg\" alt=\"\" class=\"wp-image-98035\" srcset=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2022\/08\/grignetta.jpg 1024w, https:\/\/smilingway.cz\/wp-content\/uploads\/2022\/08\/grignetta-300x188.jpg 300w, https:\/\/smilingway.cz\/wp-content\/uploads\/2022\/08\/grignetta-768x480.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\"><em>Grignetta<\/em><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Aufstieg zur Nordgrigna <\/strong>&#8211; die Wanderung zur Nordgrigna ist besonders f\u00fcr diejenigen geeignet, die im zentralen Teil des Sees wohnen (Varenna, Bellagio, etc.). Parken Sie Ihr Auto in dem kleinen Skidorf Cainallo in der N\u00e4he des V\u00f3 di Moncodeno-Passes, wo Sie eine der Pisten w\u00e4hlen k\u00f6nnen:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a aria-label=\"Trasa na horu Grigna p\u0159es chatu Rifugio Arnaldo Bogani (otev\u0159e se na nov\u00e9 z\u00e1lo\u017ece)\" href=\"https:\/\/mapy.cz\/s\/3qzdP\" target=\"_blank\" rel=\"noreferrer noopener\">Route zum Monte Grigna \u00fcber die Arnaldo-Bogani-H\u00fctte (Rifugio Arnaldo Bogani)<\/a><\/li>\n\n\n\n<li><a aria-label=\"Trasa na horuGrigna p\u0159es chatu Rifugio Bietti Buzzi (otev\u0159e se na nov\u00e9 z\u00e1lo\u017ece)\" href=\"https:\/\/mapy.cz\/s\/3qze0\" target=\"_blank\" rel=\"noreferrer noopener\">Route nach Grigna \u00fcber die Bietti-Buzzi-H\u00fctte (Rifugio Bietti Buzzi)<\/a><br><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"ubytovani-u-lago-di-como\">Unterk\u00fcnfte in der N\u00e4he des Lago di Como<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong><a href=\"https:\/\/www.booking.com\/hotel\/it\/park-abbadia.cs.html?aid=1858944&amp;no_rooms=1&amp;group_adults=2\" target=\"_blank\" rel=\"noreferrer noopener\">Hotel Abbadia<\/a>:<\/strong> Gem\u00fctliches Hotel, nur wenige Schritte vom See entfernt, mit Garten und guter Anbindung an den See (Varenna, Bellagio) und Bergamo<\/li>\n\n\n\n<li><a href=\"https:\/\/www.booking.com\/hotel\/it\/residence-alessandra-domaso12.cs.html?aid=1858944&amp;no_rooms=1&amp;group_adults=2\" target=\"_blank\" rel=\"noreferrer noopener\">\n  <strong>Residenz Alessandra:<\/strong>\n<\/a> Moderne Wohnungen im Nordwesten des Sees, mit Schwimmbad, Garten und Parkplatz<\/li>\n\n\n\n<li><a href=\"https:\/\/www.booking.com\/hotel\/it\/vista-lago.cs.html?aid=1858944&amp;no_rooms=1&amp;group_adults=2\" target=\"_blank\" rel=\"noreferrer noopener\">\n  <strong>Hotel Vista Lago:<\/strong>\n<\/a> Gem\u00fctliches 3*-Hotel im Bergdorf Brunate, ideal f\u00fcr Wanderungen und spektakul\u00e4re Aussichten  <\/li>\n\n\n\n<li><strong>\n  <a href=\"https:\/\/www.booking.com\/hotel\/it\/il-loggiato-dei-serviti.cs.html?aid=1858944&amp;no_rooms=1&amp;group_adults=2\" target=\"_blank\" rel=\"noreferrer noopener\">Hotel Il Loggiato Dei Serviti:<\/a>\n<\/strong> Saubere und praktische Unterkunft in der Stadt Como am westlichen Ende des Sees<\/li>\n<\/ul>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-cb123a13 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-8e29bb04\"><h4 class=\"uagb-heading-text\">Unterkunft Lago di Como \ud83d\ude34<\/h4><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-fd6bb0ed alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-bc3c1c67\">\n<div class=\"wp-block-uagb-info-box uagb-block-72883329 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top uagb-infobox_cta-type-all\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-image-content\"><img decoding=\"async\" src=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/02\/ubytovani-lago-di-como.jpeg\" alt=\"ubytov\u00e1n\u00ed lago di como\" width=\"700\" height=\"400\" loading=\"lazy\"\/><\/div><div class=\"uagb-ifb-title-wrap\"><h5 class=\"uagb-ifb-title\">Hotel Abbadia<\/h5><\/div><p class=\"uagb-ifb-desc\">Gem\u00fctliches Hotel nur einen kurzen Spaziergang vom See entfernt + gute Erreichbarkeit<\/p><div class=\"uagb-ifb-button-wrapper wp-block-button\"><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-80ff24bb\">\n<div class=\"wp-block-uagb-info-box uagb-block-97d9f7dc uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top uagb-infobox_cta-type-all\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-image-content\"><img decoding=\"async\" src=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/02\/ubytovani-lago-di-como-2.jpeg\" alt=\"ubytov\u00e1n\u00ed lago di como\" width=\"700\" height=\"400\" loading=\"lazy\"\/><\/div><div class=\"uagb-ifb-title-wrap\"><h5 class=\"uagb-ifb-title\">Wohnsitz Alessandra<\/h5><\/div><p class=\"uagb-ifb-desc\">Wohnungen mit Schwimmbad im Nordwesten des Sees<\/p><div class=\"uagb-ifb-button-wrapper wp-block-button\"><\/div><\/div><\/div>\n<\/div>\n<\/div><\/div>\n<\/div>\n\n\n\n<div style=\"height:31px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"jak-se-dostat-k-jezeru-z-cr\">Wie man zum Comer See kommt<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Der Lago Como liegt in den Provinzen Como und Lecco in der <a href=\"https:\/\/smilingway.cz\/de\/lombardei-italien\/\" target=\"_blank\" rel=\"noreferrer noopener\">Lombardei<\/a> und bildet den westlichen Rand der Bergamasker Alpen, die den See buchst\u00e4blich umschlie\u00dfen. Sie ragen wie Fjorde aus dem Wasser.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como ist gut mit <a href=\"https:\/\/smilingway.cz\/de\/mailand\/\" target=\"_blank\" rel=\"noreferrer noopener\">Mailand<\/a> verbunden. Lecco ist sowohl mit Mailand als auch mit <a href=\"https:\/\/smilingway.cz\/de\/bergamo-italien\/\" target=\"_blank\" rel=\"noreferrer noopener\">Bergamo<\/a>, wo sich der Flughafen Orio Al Serio befindet, gut verbunden. Das touristisch interessanteste Gebiet ist das Zentrum des Sees mit den St\u00e4dten Bellagio und Varenna.  <\/p>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center\" id=\"letecky-k-lago-di-como\">Mit dem Flugzeug zum Lago di Como<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Der Lago di Como ist mit dem Flugzeug sehr gut erreichbar, da es in der N\u00e4he 3 Flugh\u00e4fen gibt:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Bergamo Orio Al Serio Airport (BGY) &#8211; Der Flughafen Bergamo befindet sich am Stadtrand von Bergamo.<\/li>\n\n\n\n<li>Flughafen Malpensa (MXP) &#8211; Der Flughafen Malpensa liegt nordwestlich von Mailand.<\/li>\n\n\n\n<li>Flughafen Linate (LIN) &#8211; dieser Flughafen befindet sich am Stadtrand von Mailand<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading has-text-align-center\">Wie man von Bergamo zum Comer See kommt<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Am Flughafen Orio Al Serio in Bergamo nehmen Sie den Bus Nr. 1 nach <a href=\"https:\/\/smilingway.cz\/de\/bergamo-italien\/\" target=\"_blank\" rel=\"noreferrer noopener\">Bergamo<\/a>, die h\u00e4ufig und regelm\u00e4\u00dfig verkehrt. Sie k\u00f6nnen Ihr Ticket am Informationsschalter oder am Ticketautomaten am Ausgang des Terminals kaufen. Der Preis betr\u00e4gt 3 \u20ac. Das Ticket ist 90 Minuten lang g\u00fcltig und kann auch f\u00fcr andere Verkehrsmittel innerhalb Bergamos verwendet werden, einschlie\u00dflich der Seilbahn nach Citt\u00e0 Alta.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Steigen Sie am Bahnhof und Busbahnhof aus (15-20 Minuten vom Flughafen entfernt), wo Sie direkt einen Zug nach Lecco an der S\u00fcdspitze des Comer Sees nehmen k\u00f6nnen.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Eine Fahrkarte nach Lecco kostet 4 \u20ac und die Fahrt dauert 40 Minuten. Die Z\u00fcge fahren regelm\u00e4\u00dfig im Stundentakt zwischen 6:08-22:08 Uhr. Sie k\u00f6nnen Ihr Ticket auch <a href=\"https:\/\/www.trenitalia.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">online<\/a> kaufen.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es bleibt Ihnen \u00fcberlassen, ob Sie in Lecco bleiben oder weiter nach Norden in Richtung Varenna fahren, wo die F\u00e4hren nach Bellagio ablegen. Die Strecke Lecco-Varenna kostet 3,10 \u20ac und dauert je nach Verbindung 22-38 Minuten. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Unterwegs h\u00e4lt der Zug an mehreren Orten der Ostk\u00fcste, darunter Mandello Del Lario und Lierna. Von Varenna aus k\u00f6nnen Sie die F\u00e4hre nach Bellagio oder Menaggio nehmen.  <\/p>\n\n\n\n<h4 class=\"wp-block-heading has-text-align-center\" id=\"spojeni-milano-lago-di-como\">Wie man von Mailand zum Comer See kommt<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Sie kommen am Flughafen Malpensa an? Der Flughafen Malpensa befindet sich im Nordwesten von <a href=\"https:\/\/smilingway.cz\/de\/mailand\/\" target=\"_blank\" rel=\"noreferrer noopener\">Mailand<\/a>. Sie k\u00f6nnen zwischen direkten Bussen oder Malpensa Express Z\u00fcgen w\u00e4hlen. Wenn Sie am Flughafen angekommen sind, folgen Sie den Schildern, um zu sehen, welches Verkehrsmittel Sie f\u00fcr das Stadtzentrum gew\u00e4hlt haben.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der Flughafenbus kostet 10 \u20ac und die Fahrkarten k\u00f6nnen <a href=\"https:\/\/www.getyourguide.com\/milan-malpensa-airport-l96148\/bus-transfer-from-malpensa-airport-and-milan-central-station-t266412\/?partner_id=8ABF128&amp;utm_medium=online_publisher&amp;placement=content-middle\" target=\"_blank\" rel=\"noreferrer noopener\">online gebucht<\/a> werden. Dann zeigen Sie es einfach auf Ihrem Handy vor Ort an. Wenn Sie die n\u00e4chstgelegene Verbindung verpassen, k\u00f6nnen Sie ohne Probleme die n\u00e4chste nehmen. Die Fahrt zum Hauptbahnhof dauert 50 Minuten.  <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/145-1-1.jpg\"><img decoding=\"async\" width=\"853\" height=\"640\" src=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/145-1-1.jpg\" alt=\"\" class=\"wp-image-121934\" srcset=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/145-1-1.jpg 853w, https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/145-1-1-300x225.jpg 300w, https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/145-1-1-768x576.jpg 768w\" sizes=\"(max-width: 853px) 100vw, 853px\" \/><\/a><figcaption class=\"wp-element-caption\"><em>Busse von Malpensa Flughafen nach Milano Centrale Station<\/em><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Der <a href=\"https:\/\/www.malpensaexpress.it\/en\/\" target=\"_blank\" rel=\"noreferrer noopener\">Malpensa Express<\/a> kostet 13 \u20ac, ist daf\u00fcr aber bequemer. Der Hauptbahnhof ist in weniger als einer Stunde zu erreichen.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Am Bahnhof Centrale nehmen Sie den Zug nach Como, das am Ende des linken Seeufers liegt. Das Ticket kostet 5,20 \u20ac und die Fahrt zum Bahnhof S. Giovanni Centrale in Como dauert 39 Minuten. Direkte Z\u00fcge verkehren einmal pro Stunde zwischen 6:43 und 21:43 Uhr.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a aria-label=\"italsk\u00e9ho vlakov\u00e9ho spojen\u00ed Trenitalia (otev\u0159e se na nov\u00e9 z\u00e1lo\u017ece)\" href=\"https:\/\/www.trenitalia.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Auf den italienischen Zugseiten von Trenitalia<\/a> finden Sie alle Zugverbindungen in Italien.<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center\" id=\"autem-k-lago-di-como\">Mit dem Auto zum Lago di Como  <\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Der Comer See liegt in Norditalien in der <a href=\"https:\/\/smilingway.cz\/de\/lombardei-italien\/\" target=\"_blank\" rel=\"noreferrer noopener\">Lombardei<\/a>, wo es ein ausgezeichnetes Netz von guten Stra\u00dfen gibt. Auf dem Weg fallen Geb\u00fchren an, die je nach Ausgangspunkt und Aufenthaltsort am See variieren.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Wenn Sie \u00fcber Innsbruck, \u00d6sterreich, fahren, fallen folgende Geb\u00fchren an:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Eine Autobahnvignette f\u00fcr \u00d6sterreich f\u00fcr 11,50 \u20ac f\u00fcr 10 Tage (Motorr\u00e4der 4,60 \u20ac).<\/li>\n\n\n\n<li>Bezahlung f\u00fcr die \u00dcberquerung des Brennerpasses zwischen Innsbruck und der \u00f6sterreichisch-italienischen Grenze 11 \u20ac<\/li>\n\n\n\n<li>Die Maut <a href=\"https:\/\/smilingway.cz\/de\/reiseziele-in-italien\/\" target=\"_blank\" rel=\"noreferrer noopener\">in Italien<\/a> betr\u00e4gt etwa 8-9 \u20ac pro 100 km. Sie k\u00f6nnen die Maut in bar oder mit Karte bezahlen. Jedes Zahlungsportal hat oben ein Symbol, das anzeigt, wie Sie bezahlen k\u00f6nnen.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/shop.asfinag.at\/en\" target=\"_blank\" rel=\"noreferrer noopener\">Die Brenner-Pass-Vignette und die Bezahlung f\u00fcr \u00d6sterreich<\/a> k\u00f6nnen online an einem Ort erworben werden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Wenn Sie aus Wien kommen<\/strong>, fahren Sie nicht \u00fcber den Brennerpass. Auf der anderen Seite werden Sie mehr Mautgeb\u00fchren zahlen m\u00fcssen. Sie k\u00f6nnen die Mautgeb\u00fchr <a href=\"https:\/\/www.autostrade.it\/it\/home\" target=\"_blank\" rel=\"noreferrer noopener\">hier berechnen<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Geb\u00fchren bei der Durchreise durch die Schweiz: <\/strong> <a href=\"https:\/\/www.ch.ch\/en\/vehicles-and-traffic\/how-to-behave-in-road-traffic\/motorway-vignette\/\" target=\"_blank\" rel=\"noreferrer noopener\">Die Schweizer Vignette<\/a> f\u00fcr CHF 40. Sie ist teurer, weil nur Vignetten mit einer G\u00fcltigkeitsdauer von einem Jahr verkauft werden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Preise f\u00fcr Benzin und Diesel variieren von Land zu Land. <a href=\"https:\/\/www.tolls.eu\/fuel-prices\" target=\"_blank\" rel=\"noreferrer noopener\">Die aktuellen Kraftstoffpreise<\/a> finden Sie unter <a href=\"https:\/\/www.tolls.eu\/fuel-prices\" target=\"_blank\" rel=\"noreferrer noopener\">diesem Link<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Unter diesem Link finden Sie aktuelle Informationen zum <a href=\"https:\/\/www.autostrade.it\/en\/home\" target=\"_blank\" rel=\"noreferrer noopener\">Verkehr in Italien<\/a> (Mautgeb\u00fchren, Sperrungen usw.). Auch Google Maps liefert Ihnen ausreichend Informationen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"doprava-u-lago-di-como\">Transport am Lago di Como<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Der Wassertransport ist eine geeignete Transportm\u00f6glichkeit am See. Es werden Motorboote und F\u00e4hren angeboten. Das h\u00e4ngt davon ab, wohin und von wo aus Sie fahren m\u00fcssen.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Auf den Strecken verkehren <strong>Motorboote<\/strong>:  <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Como &#8211; Colico<\/li>\n\n\n\n<li>Colico &#8211; Como<\/li>\n\n\n\n<li>Ferienanlagen im zentralen Teil des Sees<\/li>\n\n\n\n<li>Lecco &#8211; Bellagio &#8211; Lecco<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Die <strong>F\u00e4hre<\/strong> verbindet die zentralen Ferienorte Cadenabbia &#8211; Varenna &#8211; Menaggio &#8211; Bellagio und verkehrt im Viertelstundentakt. <a href=\"https:\/\/www.navigazionelaghi.it\/doc\/pdf\/biglietti\/como\/Tariffe%20viaggiatori.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Die Preisliste f\u00fcr die F\u00e4hre<\/a> finden Sie hier. Die aktuellen Preise finden Sie auch auf dem Bahnsteig auf einem gro\u00dfen Schild.  <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_133307.jpg\"><img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_133307.jpg\" alt=\"Bahnsteig in Bellagio \/ F\u00e4hre \u00fcber den Lago di Como\" class=\"wp-image-122033\" srcset=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_133307.jpg 1024w, https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_133307-300x225.jpg 300w, https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_133307-768x576.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\"><em>Bahnsteig in Bellagio<\/em> <em>\/ F\u00e4hre \u00fcber den Lago di Como<\/em><\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_132913.jpg\"><img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_132913.jpg\" alt=\"F\u00e4hre Lago di Como  \" class=\"wp-image-122038\" srcset=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_132913.jpg 1024w, https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_132913-300x225.jpg 300w, https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_132913-768x576.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\"><em>F\u00e4hre Lago di Como<\/em><\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_143609.jpg\"><img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_143609.jpg\" alt=\"Bahnsteig Bellagio \/ F\u00e4hre Lago di Como\" class=\"wp-image-122043\" srcset=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_143609.jpg 1024w, https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_143609-300x225.jpg 300w, https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_143609-768x576.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Benutzen Sie die F\u00e4hre, um Ihr Fahrzeug zu transportieren. So ersparen Sie sich einen langen Umweg um den See. Der Preis der Fahrkarten variiert je nach L\u00e4nge des Fahrzeugs. Hier finden Sie detaillierte Informationen \u00fcber die <a href=\"https:\/\/www.navigazionelaghi.it\/biglietti-e-orari-lago-di-como\/\" target=\"_blank\" rel=\"noreferrer noopener\">F\u00e4hren am Lago di Como.<\/a> <\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"pocasi-u-komskeho-jezera\">Wetter am Comer See<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00f6chten Sie schwimmen und das warme Wetter genie\u00dfen? Fahren Sie von Juni bis August an den See.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der Januar ist der k\u00e4lteste Monat, aber daf\u00fcr gibt es viel weniger Touristen und Sie k\u00f6nnen das sonst so \u00fcberf\u00fcllte Bellagio ganz f\u00fcr sich allein genie\u00dfen.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der Kompromiss ist dann April-Mai und September-Oktober. Die Temperaturen sind angenehm und es gibt gerade genug Touristen. Besonders der Herbst ist ideal f\u00fcr Wanderungen rund um den See.  <\/p>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-ac83c8c5 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-2f290585\"><h4 class=\"uagb-heading-text\">Unterkunft Lago di Como \ud83d\ude34<\/h4><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-b1d72dc5 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-9e622077\">\n<div class=\"wp-block-uagb-info-box uagb-block-d0e7e77c uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top uagb-infobox_cta-type-all\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-image-content\"><img decoding=\"async\" src=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/02\/ubytovani-lago-di-como-3.jpeg\" alt=\"ubytov\u00e1n\u00ed lago di como\" width=\"700\" height=\"400\" loading=\"lazy\"\/><\/div><div class=\"uagb-ifb-title-wrap\"><h5 class=\"uagb-ifb-title\">Hotel Vista Lago<\/h5><\/div><p class=\"uagb-ifb-desc\">Gem\u00fctliches Hotel mit herrlichem Blick <\/p><div class=\"uagb-ifb-button-wrapper wp-block-button\"><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-5a5434b8\">\n<div class=\"wp-block-uagb-info-box uagb-block-a23805b1 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top uagb-infobox_cta-type-all\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-image-content\"><img decoding=\"async\" src=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/02\/ubytovani-lago-di-como-4.jpeg\" alt=\"ubytov\u00e1n\u00ed lago di como\" width=\"700\" height=\"400\" loading=\"lazy\"\/><\/div><div class=\"uagb-ifb-title-wrap\"><h5 class=\"uagb-ifb-title\">Hotel Il Loggiato Dei Serviti<\/h5><\/div><p class=\"uagb-ifb-desc\">Unterk\u00fcnfte in Como mit hoher Verf\u00fcgbarkeit<\/p><div class=\"uagb-ifb-button-wrapper wp-block-button\"><\/div><\/div><\/div>\n<\/div>\n<\/div><\/div>\n<\/div>\n\n\n\n<div style=\"height:26px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"ceny-u-komskeho-jezera\">Preise am Comer See<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Die Preise in der Lombardei sind im Allgemeinen etwas h\u00f6her als in anderen Teilen Italiens. In der <a href=\"https:\/\/smilingway.cz\/de\/lombardei-italien\/\" target=\"_blank\" rel=\"noreferrer noopener\">Lombardei<\/a>gilt dies insbesondere f\u00fcr Mailand und die touristischen Gebiete am Comer See (Varenna, Bellagio). Die folgenden Preise gelten f\u00fcr Mailand und sind f\u00fcr den gr\u00f6\u00dften Teil der Lombardei etwas niedriger.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">F\u00fcr eine Mahlzeit in einem billigen Restaurant zahlen Sie etwa 20 \u20ac, f\u00fcr ein 3-G\u00e4nge-Men\u00fc f\u00fcr zwei Personen etwa 80 \u20ac. Die Preise f\u00fcr Grundnahrungsmittel sind wie folgt:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Milch 1 l &#8211; 1,43 \u20ac<\/li>\n\n\n\n<li>Wei\u00dfbrot 500 g &#8211; 2,27 \u20ac<\/li>\n\n\n\n<li>Eier 12 St\u00fcck &#8211; 3,53 \u20ac<\/li>\n\n\n\n<li>K\u00e4se 1 kg &#8211; 13,82 \u20ac<\/li>\n\n\n\n<li>H\u00e4hnchenbrust 1 kg &#8211; 10,30 \u20ac<\/li>\n\n\n\n<li>Bananen 1 kg &#8211; 1,88 \u20ac<\/li>\n\n\n\n<li>Wasser 1,5 l &#8211; 0,47 \u20ac<\/li>\n\n\n\n<li>Kartoffeln 1 kg &#8211; 1,44 \u20ac<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"prakticke-informace-pred-cestou-k-lago-di-como\">Praktische Informationen vor der Reise an den Lago di Como<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>W\u00e4hrung:<\/strong> Euro (EUR)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Bezahlen:<\/strong> F\u00fcr kleine Eink\u00e4ufe und Zahlungen ist es weniger wichtig, Bargeld bei sich zu haben, aber ansonsten k\u00f6nnen Sie in den meisten Gesch\u00e4ften mit Karte bezahlen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Steckdose: <\/strong>230 V AC. In Italien werden Steckdosen der Typen C, F und L verwendet. Die Typen C und F sind mit den meisten Steckdosen in Europa kompatibel. Auch in Hotels und anderen touristischen Einrichtungen gibt es sie. Steckdosen des Typs L sind vor allem in \u00e4lteren H\u00e4usern zu finden. Es ist besser, einen Verkleinerer einzupacken, aber den kann man in fast jedem Gesch\u00e4ft f\u00fcr ein paar Dutzend Kronen kaufen, wenn man ihn braucht.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sprache:<\/strong> Die offizielle Sprache ist Italienisch. In Touristengebieten und Hotels kann man in der Regel auch <a href=\"https:\/\/smilingway.cz\/jak-se-naucit-anglicky\/\" target=\"_blank\" rel=\"noreferrer noopener\">Englisch<\/a> sprechen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sicherheit: <\/strong>Der Lago di Como liegt in der Lombardei, die allgemein als sicheres Gebiet gilt. In den touristischeren Orten (z. B. Bellagio) besteht die \u00fcbliche Gefahr von Taschendiebst\u00e4hlen, also passen Sie gut auf Ihre Sachen auf und verstecken Sie sie gut.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_110240.jpg\"><img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_110240.jpg\" alt=\"Varenna Lago di Como\" class=\"wp-image-122083\" srcset=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_110240.jpg 1024w, https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_110240-300x225.jpg 300w, https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/01\/IMG_20180127_110240-768x576.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\"><em>Varenna Lago di Como<\/em><\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\">Die besten Buchungsm\u00f6glichkeiten f\u00fcr den Besuch des Lago di Como<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\n  <a href=\"https:\/\/www.booking.com\/searchresults.cs.html?city=-124918&amp;aid=1858944&amp;no_rooms=1&amp;group_adults=2\" target=\"_blank\" rel=\"noreferrer noopener\">\u00dcber Booking.com<\/a>\n<\/strong> suchen wir nach allen Unterk\u00fcnften. Es ist das gr\u00f6\u00dfte Unterkunftsportal der Welt, und Sie finden hier alles, von modernen Hotels \u00fcber gem\u00fctliche Pensionen bis hin zu Villen am Meer.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"https:\/\/www.getyourguide.com\/pisa-l157\/skip-the-line-ticket-leaning-tower-of-pisa-cathedral-t51230\/?partner_id=8ABF128&amp;utm_medium=online_publisher&amp;placement=content-middle\" target=\"_blank\" rel=\"noreferrer noopener\">Get Your Guide<\/a><\/strong> ist ein riesiges Buchungssystem f\u00fcr den Kauf von Eintrittskarten, F\u00fchrungen und allen m\u00f6glichen Aktivit\u00e4ten. An einem Ort k\u00f6nnen Sie die Erfahrungen anderer Reisender lesen und Tickets f\u00fcr die Vatikanischen Museen, eine Kreuzfahrt auf der Donau oder eine W\u00fcstensafari in Dubai buchen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn Sie planen, ein Auto in Lombardei zu mieten, haben wir die beste Erfahrung mit <strong>\n  <a href=\"https:\/\/rentalcars.tp.st\/qWHiA2fD\" target=\"_blank\" rel=\"noreferrer noopener\">Rentalcars.com<\/a>\n<\/strong>die die gr\u00f6\u00dfte Auswahl zu guten Preisen hat. Versicherung und kostenlose Stornierung sind eine Selbstverst\u00e4ndlichkeit.  <\/p>\n\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><strong>Wenn Sie eine Frage zu diesem Reisef\u00fchrer f\u00fcr den Lago di Como haben, schreiben Sie uns in die Kommentare unten. Wir w\u00fcnschen Ihnen eine gute Reise!<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\">Mehr Informationen \u00fcber Italien<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>LOMBARDIA: <\/strong>In der Lombardei gibt es noch viele andere sch\u00f6ne Orte zu sehen &#8211; mehr dazu in unserer Liste der Sehensw\u00fcrdigkeiten <a href=\"https:\/\/smilingway.cz\/de\/lombardei-italien\/\">in der Lombardei<\/a>.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/smilingway.cz\/de\/mailand\/\">Mailand<\/a> ist die Hauptstadt der Lombardei und ber\u00fchmt f\u00fcr ihren pr\u00e4chtigen Dom. Weitere Tipps und praktische Informationen zu Unterk\u00fcnften in Mailand finden Sie in unserem Leitfaden f\u00fcr <a href=\"https:\/\/smilingway.cz\/de\/unterkunft-in-mailand\/\">Unterk\u00fcnfte in Mailand<\/a> (g\u00fcnstige Unterk\u00fcnfte, Verbindungen zum Flughafen und zu Sehensw\u00fcrdigkeiten, Karte).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Oder werfen Sie einen Blick auf unsere <a href=\"https:\/\/smilingway.cz\/de\/bergamo-italien\/\">15 Tipps, was Sie in Bergamo sehen sollten.<\/a> Hier finden Sie mehr als 30 Tipps f\u00fcr einen <a href=\"https:\/\/smilingway.cz\/lago-di-garda-italie\/\" target=\"_blank\" rel=\"noreferrer noopener\">Besuch am Gardasee<\/a> sowie weitere n\u00fctzliche Informationen.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>NORDITALIEN: <\/strong>Lassen Sie sich von dieser Liste der sch\u00f6nsten Orte <a href=\"https:\/\/smilingway.cz\/severni-italie\/\">in Norditalien<\/a> inspirieren, die Sie <a href=\"https:\/\/smilingway.cz\/severni-italie\/\">besuchen<\/a> k\u00f6nnen, einschlie\u00dflich einer Karte.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>ITALIEN:<\/strong> Lassen Sie sich von den <a href=\"https:\/\/smilingway.cz\/de\/reiseziele-in-italien\/\">sch\u00f6nsten Orten in Italien<\/a> inspirieren.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>ROM:<\/strong> <a href=\"https:\/\/smilingway.cz\/de\/nach-rom-reisen\/\">Rom<\/a> ist eine der beliebtesten St\u00e4dte in Europa. Hier finden Sie eine Liste der besten Sehensw\u00fcrdigkeiten <a href=\"https:\/\/smilingway.cz\/de\/rome-sehenswurdigkeiten-eintrittspreise\/\">in Rom<\/a>. Stellen Sie Ihre <a href=\"https:\/\/smilingway.cz\/de\/wie-man-in-rom-spart\/\">3-t\u00e4gige Rom-Reiseroute<\/a> zusammen und sehen Sie, wie Sie in Rom sparen k\u00f6nnen. Erfahren Sie alles \u00fcber die <a href=\"https:\/\/smilingway.cz\/de\/vatikanische-museen\/\">Vatikanischen Museen<\/a> oder das <a href=\"https:\/\/smilingway.cz\/de\/kolosseum-rom\/\">Kolosseum<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>VENEDIG:<\/strong> In dem Artikel <a href=\"https:\/\/smilingway.cz\/de\/venedig-sehenswurdigkeiten\/\">Was man in Venedig besichtigen sollte<\/a> geben wir Ihnen Tipps zu den sch\u00f6nsten Orten und andere n\u00fctzliche Hinweise.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>TUSCANY <\/strong>: <a href=\"https:\/\/smilingway.cz\/de\/florenz-reisefuhrer\/\">Florenz<\/a> darf bei einem Besuch in der Toskana nicht fehlen. Sehen Sie die <a href=\"https:\/\/smilingway.cz\/de\/florenz-sehenswuerdigkeiten\/\">sch\u00f6nsten Orte in Florenz<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/smilingway.cz\/de\/pisa\/\">Pisa<\/a> ist eine weitere wunderbare Stadt in der Toskana, die es zu besichtigen gilt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>DOLOMITI<\/strong>: Eine der sch\u00f6nsten Gebirgsketten der Welt befindet sich in Norditalien. <a href=\"https:\/\/smilingway.cz\/dolomity-nejkrasnejsi-mista\/\">Was es in den Dolomiten zu sehen<\/a> gibt, steht in einem separaten Artikel. <a href=\"https:\/\/smilingway.cz\/dolomity-pruvodce\/\">Im Dolomiten-F\u00fchrer<\/a> geben wir Ihnen n\u00fctzliche Tipps f\u00fcr die Planung Ihrer Reise in die Dolomiten.<\/p>\n\n\n\n<p class=\"has-text-align-center has-ast-global-color-6-background-color has-background wp-block-paragraph\" style=\"font-size:22px\">Lesen Sie noch mehr Tipps zum <a href=\"https:\/\/smilingway.cz\/de\/italien-reisefuhrer\/\">Reisen in Italien<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\">Zusammenfassung: Lago di Como<\/h2>\n\n\n\n<div class=\"schema-faq wp-block-yoast-faq-block\"><div class=\"schema-faq-section\" id=\"faq-question-1674390640229\"><strong class=\"schema-faq-question\">Warum den Lago di Como besuchen?  <\/strong> <p class=\"schema-faq-answer\">Der Lago di Como ist ein wundersch\u00f6ner Alpensee mit kristallklarem Wasser, umgeben von den Gipfeln der Alpen. Au\u00dferdem ist es warm und man kann im Sommer problemlos schwimmen gehen. Die Ufer des Lago di Como sind ges\u00e4umt von bunten H\u00e4usern, alten Booten und Blumen. Es ist zu jeder Jahreszeit ein wunderbares Schauspiel.  <\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1674390749411\"><strong class=\"schema-faq-question\">Wie kommt man zum Lago di Como?  <\/strong> <p class=\"schema-faq-answer\">Der Comer See ist sowohl mit dem Auto als auch mit dem Flugzeug gut erreichbar. Wenn Sie mit dem Flugzeug kommen, nehmen Sie den Zug vom Flughafen nach Mailand oder Bergamo. In einer halben Stunde sind Sie an der Ziellinie. Eine ausf\u00fchrliche Beschreibung der Routen und Geb\u00fchren (ob mit dem Auto oder mit dem Flugzeug) finden Sie in diesem Artikel.  <\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1674391019602\"><strong class=\"schema-faq-question\">Welches sind die sch\u00f6nsten Orte, die man am Lago di Como besuchen kann?  <\/strong> <p class=\"schema-faq-answer\">Das Beste sehen Sie im zentralen Teil des Sees &#8211; die St\u00e4dte Varenna und Bellagio, die mit einer F\u00e4hre verbunden sind. Schlendern Sie durch die engen, verwinkelten Gassen und \u00fcber die Promenade, besuchen Sie die charmanten Pl\u00e4tze und genie\u00dfen Sie die Aussicht von der F\u00e4hre aus. Der Lago di Como ist auch ideal f\u00fcr Wanderungen auf den umliegenden Gipfeln. Weitere Tipps zu Ausflugszielen und Wanderungen finden Sie in diesem Artikel.  <\/p> <\/div> <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Der Lago di Como ist einer der sch\u00f6nsten Seen Italiens. Ber\u00fchmtheiten wie George Clooney, Giovanni Versace, Lionel Messi und Madonna haben sich hier niedergelassen. Der [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":98130,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":null,"ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":null,"ast-hfb-below-header-display":null,"ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":null,"ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":null,"stick-header-meta":null,"header-above-stick-meta":null,"header-main-stick-meta":null,"header-below-stick-meta":null,"astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[352,353,340],"tags":[499,498,647],"class_list":["post-129637","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italien","category-reisen-in-europa","category-ziel","tag-lombardei","tag-norditalien","tag-wo-man-ans-meer-fahren-kann"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lago di Como 2026: Sehensw\u00fcrdigkeiten, Reisef\u00fchrer und n\u00fctzliche Tipps<\/title>\n<meta name=\"description\" content=\"Reisef\u00fchrer f\u00fcr den Lago di Como: Sehensw\u00fcrdigkeiten, Badem\u00f6glichkeiten und die sch\u00f6nsten Str\u00e4nde, Wanderungen und Trekking in der Region, Transport, F\u00e4hren, Unterk\u00fcnfte.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/smilingway.cz\/de\/lago-di-como-italien\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lago di Como 2026: Sehensw\u00fcrdigkeiten, Reisef\u00fchrer und n\u00fctzliche Tipps\" \/>\n<meta property=\"og:description\" content=\"Reisef\u00fchrer f\u00fcr den Lago di Como: Sehensw\u00fcrdigkeiten, Badem\u00f6glichkeiten und die sch\u00f6nsten Str\u00e4nde, Wanderungen und Trekking in der Region, Transport, F\u00e4hren, Unterk\u00fcnfte.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/smilingway.cz\/de\/lago-di-como-italien\/\" \/>\n<meta property=\"og:site_name\" content=\"SMILING WAY\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/smilingwaycz\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/smilingwaycz\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-02T19:28:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-12T04:58:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/smilingway.cz\/wp-content\/uploads\/2022\/08\/lago-di-como-hlavni-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"844\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Blanka\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@smilingwaycz\" \/>\n<meta name=\"twitter:site\" content=\"@smilingwaycz\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Blanka\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"24\u00a0Minuten\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lago di Como 2026: Sehensw\u00fcrdigkeiten, Reisef\u00fchrer und n\u00fctzliche Tipps","description":"Reisef\u00fchrer f\u00fcr den Lago di Como: Sehensw\u00fcrdigkeiten, Badem\u00f6glichkeiten und die sch\u00f6nsten Str\u00e4nde, Wanderungen und Trekking in der Region, Transport, F\u00e4hren, Unterk\u00fcnfte.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/smilingway.cz\/de\/lago-di-como-italien\/","og_locale":"de_DE","og_type":"article","og_title":"Lago di Como 2026: Sehensw\u00fcrdigkeiten, Reisef\u00fchrer und n\u00fctzliche Tipps","og_description":"Reisef\u00fchrer f\u00fcr den Lago di Como: Sehensw\u00fcrdigkeiten, Badem\u00f6glichkeiten und die sch\u00f6nsten Str\u00e4nde, Wanderungen und Trekking in der Region, Transport, F\u00e4hren, Unterk\u00fcnfte.","og_url":"https:\/\/smilingway.cz\/de\/lago-di-como-italien\/","og_site_name":"SMILING WAY","article_publisher":"https:\/\/www.facebook.com\/smilingwaycz\/","article_author":"https:\/\/www.facebook.com\/smilingwaycz\/","article_published_time":"2025-01-02T19:28:00+00:00","article_modified_time":"2025-12-12T04:58:41+00:00","og_image":[{"width":1500,"height":844,"url":"https:\/\/smilingway.cz\/wp-content\/uploads\/2022\/08\/lago-di-como-hlavni-2.jpg","type":"image\/jpeg"}],"author":"Blanka","twitter_card":"summary_large_image","twitter_creator":"@smilingwaycz","twitter_site":"@smilingwaycz","twitter_misc":{"Verfasst von":"Blanka","Gesch\u00e4tzte Lesezeit":"24\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/smilingway.cz\/de\/lago-di-como-italien\/#article","isPartOf":{"@id":"https:\/\/smilingway.cz\/de\/lago-di-como-italien\/"},"author":{"name":"Blanka","@id":"https:\/\/smilingway.cz\/de\/#\/schema\/person\/1bb9c7a0f759e37cc3c643cfcf64b9ee"},"headline":"Lago di Como 2026: Sehensw\u00fcrdigkeiten, Reisef\u00fchrer und n\u00fctzliche Tipps","datePublished":"2025-01-02T19:28:00+00:00","dateModified":"2025-12-12T04:58:41+00:00","mainEntityOfPage":{"@id":"https:\/\/smilingway.cz\/de\/lago-di-como-italien\/"},"wordCount":4906,"commentCount":0,"publisher":{"@id":"https:\/\/smilingway.cz\/de\/#\/schema\/person\/1bb9c7a0f759e37cc3c643cfcf64b9ee"},"image":{"@id":"https:\/\/smilingway.cz\/de\/lago-di-como-italien\/#primaryimage"},"thumbnailUrl":"https:\/\/smilingway.cz\/wp-content\/uploads\/2022\/08\/lago-di-como-hlavni-2.jpg","keywords":["Lombardei","Norditalien","wo man ans Meer fahren kann"],"articleSection":["ITALIEN","Reisen in Europa","ZIEL"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/smilingway.cz\/de\/lago-di-como-italien\/#respond"]}]},{"@type":["WebPage","FAQPage"],"@id":"https:\/\/smilingway.cz\/de\/lago-di-como-italien\/","url":"https:\/\/smilingway.cz\/de\/lago-di-como-italien\/","name":"Lago di Como 2026: Sehensw\u00fcrdigkeiten, Reisef\u00fchrer und n\u00fctzliche Tipps","isPartOf":{"@id":"https:\/\/smilingway.cz\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/smilingway.cz\/de\/lago-di-como-italien\/#primaryimage"},"image":{"@id":"https:\/\/smilingway.cz\/de\/lago-di-como-italien\/#primaryimage"},"thumbnailUrl":"https:\/\/smilingway.cz\/wp-content\/uploads\/2022\/08\/lago-di-como-hlavni-2.jpg","datePublished":"2025-01-02T19:28:00+00:00","dateModified":"2025-12-12T04:58:41+00:00","description":"Reisef\u00fchrer f\u00fcr den Lago di Como: Sehensw\u00fcrdigkeiten, Badem\u00f6glichkeiten und die sch\u00f6nsten Str\u00e4nde, Wanderungen und Trekking in der Region, Transport, F\u00e4hren, Unterk\u00fcnfte.","breadcrumb":{"@id":"https:\/\/smilingway.cz\/de\/lago-di-como-italien\/#breadcrumb"},"mainEntity":[{"@id":"https:\/\/smilingway.cz\/de\/lago-di-como-italien\/#faq-question-1674390640229"},{"@id":"https:\/\/smilingway.cz\/de\/lago-di-como-italien\/#faq-question-1674390749411"},{"@id":"https:\/\/smilingway.cz\/de\/lago-di-como-italien\/#faq-question-1674391019602"}],"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/smilingway.cz\/de\/lago-di-como-italien\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smilingway.cz\/de\/lago-di-como-italien\/#primaryimage","url":"https:\/\/smilingway.cz\/wp-content\/uploads\/2022\/08\/lago-di-como-hlavni-2.jpg","contentUrl":"https:\/\/smilingway.cz\/wp-content\/uploads\/2022\/08\/lago-di-como-hlavni-2.jpg","width":1500,"height":844,"caption":"Lago di Como"},{"@type":"BreadcrumbList","@id":"https:\/\/smilingway.cz\/de\/lago-di-como-italien\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/smilingway.cz\/de\/"},{"@type":"ListItem","position":2,"name":"Lago di Como 2026: Sehensw\u00fcrdigkeiten, Reisef\u00fchrer und n\u00fctzliche Tipps"}]},{"@type":"WebSite","@id":"https:\/\/smilingway.cz\/de\/#website","url":"https:\/\/smilingway.cz\/de\/","name":"Smiling Way","description":"Reisetipps, Inspiration und Reisef\u00fchrer","publisher":{"@id":"https:\/\/smilingway.cz\/de\/#\/schema\/person\/1bb9c7a0f759e37cc3c643cfcf64b9ee"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/smilingway.cz\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/smilingway.cz\/de\/#\/schema\/person\/1bb9c7a0f759e37cc3c643cfcf64b9ee","name":"Blanka","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/08\/IMG_20190712_115524_optimized-1-1024x768-1.jpg","url":"https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/08\/IMG_20190712_115524_optimized-1-1024x768-1.jpg","contentUrl":"https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/08\/IMG_20190712_115524_optimized-1-1024x768-1.jpg","width":1024,"height":768,"caption":"Blanka"},"logo":{"@id":"https:\/\/smilingway.cz\/wp-content\/uploads\/2023\/08\/IMG_20190712_115524_optimized-1-1024x768-1.jpg"},"sameAs":["https:\/\/www.facebook.com\/smilingwaycz\/","https:\/\/cz.pinterest.com\/smilingwaycz\/","https:\/\/x.com\/smilingwaycz"],"url":"https:\/\/smilingway.cz\/de\/author\/admin\/"},{"@type":"Question","@id":"https:\/\/smilingway.cz\/de\/lago-di-como-italien\/#faq-question-1674390640229","position":1,"url":"https:\/\/smilingway.cz\/de\/lago-di-como-italien\/#faq-question-1674390640229","name":"Pro\u010d nav\u0161t\u00edvit Lago di Como?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"Lago di Como p\u0159edstavuje n\u00e1dhern\u00e9 alpsk\u00e9 jezero s k\u0159i\u0161\u0165\u00e1lov\u011b \u010distou vodou, kterou obklopuj\u00ed vrcholky Alp. Nav\u00edc je tepl\u00e9 a v l\u00e9t\u011b se tu m\u016f\u017eete bez probl\u00e9m\u016f koupat. B\u0159ehy Lago di Como jsou lemovan\u00e9 barevn\u00fdmi domy, star\u00fdmi lod\u011bmi a kv\u011btinami. Je to n\u00e1dhern\u00e1 pod\u00edvan\u00e1 kdykoliv v pr\u016fb\u011bhu roku. ","inLanguage":"de"},"inLanguage":"de"},{"@type":"Question","@id":"https:\/\/smilingway.cz\/de\/lago-di-como-italien\/#faq-question-1674390749411","position":2,"url":"https:\/\/smilingway.cz\/de\/lago-di-como-italien\/#faq-question-1674390749411","name":"Jak se dostat k Lago di Como?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"Komsk\u00e9 jezero je velmi dob\u0159e dostupn\u00e9 autem i leteckou dopravou. Pokud polet\u00edte, z leti\u0161t\u011b dojedete do Mil\u00e1na nebo Bergama, kde nasednete na vlak. Za p\u016fl hodiny jste v c\u00edli. Podrobn\u00fd popis tras a poplatk\u016f (a\u0165 u\u017e p\u0159i cest\u011b autem nebo letecky), najdete v \u010dl\u00e1nku. ","inLanguage":"de"},"inLanguage":"de"},{"@type":"Question","@id":"https:\/\/smilingway.cz\/de\/lago-di-como-italien\/#faq-question-1674391019602","position":3,"url":"https:\/\/smilingway.cz\/de\/lago-di-como-italien\/#faq-question-1674391019602","name":"Jak\u00e1 jsou nejkr\u00e1sn\u011bj\u0161\u00ed m\u00edsta, co nav\u0161t\u00edvit u Lago di Como?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"To nejlep\u0161\u00ed uvid\u00edte v centr\u00e1ln\u00ed \u010d\u00e1sti jezera - m\u011bste\u010dka Varenna a Bellagio, kter\u00e1 propojuje trajekt. Projd\u011bte si \u00fazk\u00e9 k\u0159ivolak\u00e9 uli\u010dky a promen\u00e1du, nav\u0161tivte kouzeln\u00e1 n\u00e1m\u011bst\u00ed a u\u017eijte si v\u00fdhled z trajektu. Lago di Como je taky ide\u00e1ln\u00edm m\u00edstem pro turistiku po okoln\u00edch \u0161t\u00edtech. V\u00edce tip\u016f, co nav\u0161t\u00edvit a kam za turistikou najdete v \u010dl\u00e1nku. ","inLanguage":"de"},"inLanguage":"de"}]}},"spectra_custom_meta":{"_encloseme":["1"],"_wpml_media_duplicate":["0"],"_wpml_media_featured":["1"],"footer-adv-display":[null],"adv-header-id-meta":[null],"site-post-title":[""],"site-sidebar-layout":["default"],"ast-featured-img":[""],"theme-transparent-header-meta":["default"],"_top_nav_excluded":[""],"_cms_nav_minihome":[""],"_wp_page_template":["default"],"_thumbnail_id":["98130"],"_last_translation_edit_mode":["native-editor"],"yoast-structured-data-blocks-images-cache":["a:0:{}"],"_edit_lock":["1765515526:1"],"essb_cached_image":["https:\/\/smilingway.cz\/wp-content\/uploads\/2022\/08\/lago-di-como-hlavni-2.jpg"],"_wp_old_slug":["lago-di-como-2023-sehenswuerdigkeiten-reisefuehrer-und-nuetzliche-tipps"],"_edit_last":["1"],"_wpml_media_has_media":["1"],"_yoast_wpseo_linkdex":["73"],"_yoast_wpseo_content_score":["30"],"_yoast_wpseo_estimated-reading-time-minutes":[""],"_yoast_wpseo_wordproof_timestamp":[""],"ast-site-content-layout":["default"],"_yoast_wpseo_metadesc":["Reisef\u00fchrer f\u00fcr den Lago di Como: Sehensw\u00fcrdigkeiten, Badem\u00f6glichkeiten und die sch\u00f6nsten Str\u00e4nde, Wanderungen und Trekking in der Region, Transport, F\u00e4hren, Unterk\u00fcnfte."],"_yoast_wpseo_focuskw":["Lago di Como"],"_uag_custom_page_level_css":[""],"astra-migrate-meta-layouts":["set"],"footnotes":[""],"_yoast_wpseo_primary_category":["14"],"ast-hfb-above-header-display":[null],"ast-hfb-below-header-display":[null],"ast-above-header-display":[null],"ast-below-header-display":[null],"stick-header-meta":[null],"header-main-stick-meta":[null],"header-above-stick-meta":[null],"header-below-stick-meta":[null],"site-content-layout":[null],"ast-breadcrumbs-content":[null],"site-content-style":["default"],"site-sidebar-style":["default"],"_wpml_word_count":["4909"],"_uagb_toc_options":["a:2:{s:17:\"_uagb_toc_version\";i:1788337565;s:18:\"_uagb_toc_headings\";a:45:{i:0;a:4:{s:5:\"level\";i:2;s:2:\"id\";s:31:\"warum-den-lago-di-como-besuchen\";s:7:\"content\";s:31:\"Warum den Lago di Como besuchen\";s:5:\"depth\";i:2;}i:1;a:4:{s:5:\"level\";i:2;s:2:\"id\";s:42:\"interessante-punkte-\u00fcber-den-lago-di-como\";s:7:\"content\";s:42:\"Interessante Punkte \u00fcber den Lago di Como\";s:5:\"depth\";i:2;}i:2;a:4:{s:5:\"level\";i:2;s:2:\"id\";s:64:\"reiseziele-und-sehensw\u00fcrdigkeiten-in-der-n\u00e4he-des-lago-di-como\";s:7:\"content\";s:64:\"Reiseziele und Sehensw\u00fcrdigkeiten in der N\u00e4he des Lago di Como\";s:5:\"depth\";i:2;}i:3;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:42:\"bellagio-der-sch\u00f6nste-ort-am-lago-di-como\";s:7:\"content\";s:44:\"Bellagio - der sch\u00f6nste Ort am Lago di Como\";s:5:\"depth\";i:3;}i:4;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:52:\"varenna-ein-muss-f\u00fcr-jeden-besucher-am-lago-di-como\";s:7:\"content\";s:54:\"Varenna - ein Muss f\u00fcr jeden Besucher am Lago di Como\";s:5:\"depth\";i:3;}i:5;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:67:\"como-der-gr\u00f6\u00dfte-ferienort-am-see-mit-einer-pr\u00e4chtigen-kathedrale\";s:7:\"content\";s:69:\"Como - der gr\u00f6\u00dfte Ferienort am See mit einer pr\u00e4chtigen Kathedrale\";s:5:\"depth\";i:3;}i:6;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:22:\"bootfahren-auf-dem-see\";s:7:\"content\";s:22:\"Bootfahren auf dem See\";s:5:\"depth\";i:3;}i:7;a:4:{s:5:\"level\";i:4;s:2:\"id\";s:23:\"unterkunft-lago-di-como\";s:7:\"content\";s:28:\"Unterkunft Lago di Como \ud83d\ude34\";s:5:\"depth\";i:4;}i:8;a:4:{s:5:\"level\";i:5;s:2:\"id\";s:13:\"hotel-abbadia\";s:7:\"content\";s:13:\"Hotel Abbadia\";s:5:\"depth\";i:5;}i:9;a:4:{s:5:\"level\";i:5;s:2:\"id\";s:19:\"wohnsitz-alessandra\";s:7:\"content\";s:19:\"Wohnsitz Alessandra\";s:5:\"depth\";i:5;}i:10;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:17:\"villa-balbianello\";s:7:\"content\";s:17:\"Villa Balbianello\";s:5:\"depth\";i:3;}i:11;a:4:{s:5:\"level\";i:2;s:2:\"id\";s:34:\"baden-und-str\u00e4nde-am-lago-di-como\";s:7:\"content\";s:34:\"Baden und Str\u00e4nde am Lago di Como\";s:5:\"depth\";i:2;}i:12;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:30:\"str\u00e4nde-am-lago-di-como-karte\";s:7:\"content\";s:32:\"Str\u00e4nde am Lago di Como + Karte\";s:5:\"depth\";i:3;}i:13;a:4:{s:5:\"level\";i:4;s:2:\"id\";s:27:\"str\u00e4nde-um-como-s\u00fcdwesten\";s:7:\"content\";s:29:\"Str\u00e4nde um Como - S\u00fcdwesten\";s:5:\"depth\";i:4;}i:14;a:4:{s:5:\"level\";i:4;s:2:\"id\";s:27:\"str\u00e4nde-um-lecco-s\u00fcdosten\";s:7:\"content\";s:29:\"Str\u00e4nde um Lecco - S\u00fcdosten\";s:5:\"depth\";i:4;}i:15;a:4:{s:5:\"level\";i:4;s:2:\"id\";s:25:\"str\u00e4nde-um-colico-norden\";s:7:\"content\";s:27:\"Str\u00e4nde um Colico - Norden\";s:5:\"depth\";i:4;}i:16;a:4:{s:5:\"level\";i:2;s:2:\"id\";s:32:\"wandern-rund-um-den-lago-di-como\";s:7:\"content\";s:32:\"Wandern rund um den Lago di Como\";s:5:\"depth\";i:2;}i:17;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:28:\"besteigung-des-monte-legnone\";s:7:\"content\";s:28:\"Besteigung des Monte Legnone\";s:5:\"depth\";i:3;}i:18;a:4:{s:5:\"level\";i:4;s:2:\"id\";s:23:\"unterkunft-lago-di-como\";s:7:\"content\";s:28:\"Unterkunft Lago di Como \ud83d\ude34\";s:5:\"depth\";i:4;}i:19;a:4:{s:5:\"level\";i:5;s:2:\"id\";s:16:\"hotel-vista-lago\";s:7:\"content\";s:16:\"Hotel Vista Lago\";s:5:\"depth\";i:5;}i:20;a:4:{s:5:\"level\";i:5;s:2:\"id\";s:29:\"hotel-il-loggiato-dei-serviti\";s:7:\"content\";s:29:\"Hotel Il Loggiato Dei Serviti\";s:5:\"depth\";i:5;}i:21;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:29:\"besteigung-des-monte-bregnano\";s:7:\"content\";s:29:\"Besteigung des Monte Bregnano\";s:5:\"depth\";i:3;}i:22;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:24:\"aufstieg-zum-monte-grona\";s:7:\"content\";s:24:\"Aufstieg zum Monte Grona\";s:5:\"depth\";i:3;}i:23;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:30:\"besteigung-des-monte-palanzone\";s:7:\"content\";s:30:\"Besteigung des Monte Palanzone\";s:5:\"depth\";i:3;}i:24;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:30:\"besteigung-des-monte-san-primo\";s:7:\"content\";s:30:\"Besteigung des Monte San Primo\";s:5:\"depth\";i:3;}i:25;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:34:\"aufstieg-zum-bergmassiv-der-grigna\";s:7:\"content\";s:34:\"Aufstieg zum Bergmassiv der Grigna\";s:5:\"depth\";i:3;}i:26;a:4:{s:5:\"level\";i:2;s:2:\"id\";s:42:\"unterk\u00fcnfte-in-der-n\u00e4he-des-lago-di-como\";s:7:\"content\";s:42:\"Unterk\u00fcnfte in der N\u00e4he des Lago di Como\";s:5:\"depth\";i:2;}i:27;a:4:{s:5:\"level\";i:4;s:2:\"id\";s:23:\"unterkunft-lago-di-como\";s:7:\"content\";s:28:\"Unterkunft Lago di Como \ud83d\ude34\";s:5:\"depth\";i:4;}i:28;a:4:{s:5:\"level\";i:5;s:2:\"id\";s:13:\"hotel-abbadia\";s:7:\"content\";s:13:\"Hotel Abbadia\";s:5:\"depth\";i:5;}i:29;a:4:{s:5:\"level\";i:5;s:2:\"id\";s:19:\"wohnsitz-alessandra\";s:7:\"content\";s:19:\"Wohnsitz Alessandra\";s:5:\"depth\";i:5;}i:30;a:4:{s:5:\"level\";i:2;s:2:\"id\";s:27:\"wie-man-zum-comer-see-kommt\";s:7:\"content\";s:27:\"Wie man zum Comer See kommt\";s:5:\"depth\";i:2;}i:31;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:33:\"mit-dem-flugzeug-zum-lago-di-como\";s:7:\"content\";s:33:\"Mit dem Flugzeug zum Lago di Como\";s:5:\"depth\";i:3;}i:32;a:4:{s:5:\"level\";i:4;s:2:\"id\";s:39:\"wie-man-von-bergamo-zum-comer-see-kommt\";s:7:\"content\";s:39:\"Wie man von Bergamo zum Comer See kommt\";s:5:\"depth\";i:4;}i:33;a:4:{s:5:\"level\";i:4;s:2:\"id\";s:39:\"wie-man-von-mailand-zum-comer-see-kommt\";s:7:\"content\";s:39:\"Wie man von Mailand zum Comer See kommt\";s:5:\"depth\";i:4;}i:34;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:29:\"mit-dem-auto-zum-lago-di-como\";s:7:\"content\";s:29:\"Mit dem Auto zum Lago di Como\";s:5:\"depth\";i:3;}i:35;a:4:{s:5:\"level\";i:2;s:2:\"id\";s:25:\"transport-am-lago-di-como\";s:7:\"content\";s:25:\"Transport am Lago di Como\";s:5:\"depth\";i:2;}i:36;a:4:{s:5:\"level\";i:2;s:2:\"id\";s:19:\"wetter-am-comer-see\";s:7:\"content\";s:19:\"Wetter am Comer See\";s:5:\"depth\";i:2;}i:37;a:4:{s:5:\"level\";i:4;s:2:\"id\";s:23:\"unterkunft-lago-di-como\";s:7:\"content\";s:28:\"Unterkunft Lago di Como \ud83d\ude34\";s:5:\"depth\";i:4;}i:38;a:4:{s:5:\"level\";i:5;s:2:\"id\";s:16:\"hotel-vista-lago\";s:7:\"content\";s:16:\"Hotel Vista Lago\";s:5:\"depth\";i:5;}i:39;a:4:{s:5:\"level\";i:5;s:2:\"id\";s:29:\"hotel-il-loggiato-dei-serviti\";s:7:\"content\";s:29:\"Hotel Il Loggiato Dei Serviti\";s:5:\"depth\";i:5;}i:40;a:4:{s:5:\"level\";i:2;s:2:\"id\";s:19:\"preise-am-comer-see\";s:7:\"content\";s:19:\"Preise am Comer See\";s:5:\"depth\";i:2;}i:41;a:4:{s:5:\"level\";i:2;s:2:\"id\";s:58:\"praktische-informationen-vor-der-reise-an-den-lago-di-como\";s:7:\"content\";s:58:\"Praktische Informationen vor der Reise an den Lago di Como\";s:5:\"depth\";i:2;}i:42;a:4:{s:5:\"level\";i:2;s:2:\"id\";s:66:\"die-besten-buchungsm\u00f6glichkeiten-f\u00fcr-den-besuch-des-lago-di-como\";s:7:\"content\";s:66:\"Die besten Buchungsm\u00f6glichkeiten f\u00fcr den Besuch des Lago di Como\";s:5:\"depth\";i:2;}i:43;a:4:{s:5:\"level\";i:2;s:2:\"id\";s:32:\"mehr-informationen-\u00fcber-italien\";s:7:\"content\";s:32:\"Mehr Informationen \u00fcber Italien\";s:5:\"depth\";i:2;}i:44;a:4:{s:5:\"level\";i:2;s:2:\"id\";s:28:\"zusammenfassung-lago-di-como\";s:7:\"content\";s:29:\"Zusammenfassung: Lago di Como\";s:5:\"depth\";i:2;}}}"],"_uagb_previous_block_counts":["a:90:{s:21:\"uagb\/advanced-heading\";i:4;s:15:\"uagb\/blockquote\";i:0;s:12:\"uagb\/buttons\";i:0;s:18:\"uagb\/buttons-child\";i:0;s:19:\"uagb\/call-to-action\";i:0;s:15:\"uagb\/cf7-styler\";i:0;s:11:\"uagb\/column\";i:0;s:12:\"uagb\/columns\";i:0;s:14:\"uagb\/container\";i:16;s:21:\"uagb\/content-timeline\";i:0;s:27:\"uagb\/content-timeline-child\";i:0;s:14:\"uagb\/countdown\";i:0;s:12:\"uagb\/counter\";i:0;s:8:\"uagb\/faq\";i:0;s:14:\"uagb\/faq-child\";i:0;s:10:\"uagb\/forms\";i:0;s:17:\"uagb\/forms-accept\";i:0;s:19:\"uagb\/forms-checkbox\";i:0;s:15:\"uagb\/forms-date\";i:0;s:16:\"uagb\/forms-email\";i:0;s:17:\"uagb\/forms-hidden\";i:0;s:15:\"uagb\/forms-name\";i:0;s:16:\"uagb\/forms-phone\";i:0;s:16:\"uagb\/forms-radio\";i:0;s:17:\"uagb\/forms-select\";i:0;s:19:\"uagb\/forms-textarea\";i:0;s:17:\"uagb\/forms-toggle\";i:0;s:14:\"uagb\/forms-url\";i:0;s:14:\"uagb\/gf-styler\";i:0;s:15:\"uagb\/google-map\";i:0;s:11:\"uagb\/how-to\";i:0;s:16:\"uagb\/how-to-step\";i:0;s:9:\"uagb\/icon\";i:0;s:14:\"uagb\/icon-list\";i:0;s:20:\"uagb\/icon-list-child\";i:0;s:10:\"uagb\/image\";i:0;s:18:\"uagb\/image-gallery\";i:0;s:13:\"uagb\/info-box\";i:8;s:18:\"uagb\/inline-notice\";i:0;s:11:\"uagb\/lottie\";i:0;s:21:\"uagb\/marketing-button\";i:0;s:10:\"uagb\/modal\";i:0;s:18:\"uagb\/popup-builder\";i:0;s:16:\"uagb\/post-button\";i:0;s:18:\"uagb\/post-carousel\";i:0;s:17:\"uagb\/post-excerpt\";i:0;s:14:\"uagb\/post-grid\";i:0;s:15:\"uagb\/post-image\";i:0;s:17:\"uagb\/post-masonry\";i:0;s:14:\"uagb\/post-meta\";i:0;s:18:\"uagb\/post-taxonomy\";i:0;s:18:\"uagb\/post-timeline\";i:0;s:15:\"uagb\/post-title\";i:0;s:20:\"uagb\/restaurant-menu\";i:0;s:26:\"uagb\/restaurant-menu-child\";i:0;s:11:\"uagb\/review\";i:0;s:12:\"uagb\/section\";i:0;s:14:\"uagb\/separator\";i:0;s:11:\"uagb\/slider\";i:0;s:17:\"uagb\/slider-child\";i:0;s:17:\"uagb\/social-share\";i:0;s:23:\"uagb\/social-share-child\";i:0;s:16:\"uagb\/star-rating\";i:0;s:23:\"uagb\/sure-cart-checkout\";i:0;s:22:\"uagb\/sure-cart-product\";i:0;s:15:\"uagb\/sure-forms\";i:0;s:22:\"uagb\/table-of-contents\";i:1;s:9:\"uagb\/tabs\";i:0;s:15:\"uagb\/tabs-child\";i:0;s:18:\"uagb\/taxonomy-list\";i:0;s:9:\"uagb\/team\";i:0;s:16:\"uagb\/testimonial\";i:0;s:14:\"uagb\/wp-search\";i:0;s:19:\"uagb\/instagram-feed\";i:0;s:10:\"uagb\/login\";i:0;s:17:\"uagb\/loop-builder\";i:0;s:18:\"uagb\/loop-category\";i:0;s:20:\"uagb\/loop-pagination\";i:0;s:15:\"uagb\/loop-reset\";i:0;s:16:\"uagb\/loop-search\";i:0;s:14:\"uagb\/loop-sort\";i:0;s:17:\"uagb\/loop-wrapper\";i:0;s:13:\"uagb\/register\";i:0;s:19:\"uagb\/register-email\";i:0;s:24:\"uagb\/register-first-name\";i:0;s:23:\"uagb\/register-last-name\";i:0;s:22:\"uagb\/register-password\";i:0;s:30:\"uagb\/register-reenter-password\";i:0;s:19:\"uagb\/register-terms\";i:0;s:22:\"uagb\/register-username\";i:0;}"],"_uagb_last_spectra_edit":["1776949816"],"_uag_page_assets":["a:9:{s:3:\"css\";s:106061:\".uagb-block-be2cc2f9.wp-block-uagb-table-of-contents{text-align: left;}.uagb-block-be2cc2f9 .uagb-toc__list-wrap li a{color: #54595F;}.uagb-block-be2cc2f9 .uagb-toc__wrap .uagb-toc__title-wrap{justify-content: left;}.uagb-block-be2cc2f9 .uagb-toc__wrap .uagb-toc__title{justify-content: left;cursor: pointer;}.uagb-block-be2cc2f9 .uagb-toc__wrap{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-color: #333;border-style: solid;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;background: #fff;}.uagb-block-be2cc2f9 .uagb-toc__list-wrap{column-count: 1;overflow: hidden;text-align: left;}.uagb-block-be2cc2f9 .uagb-toc__list-wrap > ul.uagb-toc__list > li:first-child{padding-top: 0;}.uagb-block-be2cc2f9 .uagb-toc__list-wrap ul.uagb-toc__list:last-child > li:last-child{padding-bottom: 0;}.uagb-block-be2cc2f9 .uagb-toc__list .uagb-toc__list{list-style-type: disc !important;}.uagb-block-be2cc2f9 .uagb-toc__title{font-weight: Default;font-size: 20px;}.uagb-block-be2cc2f9 .uagb-toc__list-wrap ol li a{text-decoration: none;}.wp-block-uagb-container.uagb-block-e064fb7f .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-e064fb7f .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-e064fb7f .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-e064fb7f .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-e064fb7f .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e064fb7f{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-e064fb7f{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 5px;padding-left: 5px;padding-right: 5px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-top-left-radius: 10px;border-top-right-radius: 10px;border-bottom-left-radius: 10px;border-bottom-right-radius: 10px;border-color: inherit;background-color: #dce8f2;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-advanced-heading.uagb-block-ac921c3b.wp-block-uagb-advanced-heading .uagb-heading-text{color: #505050;}.wp-block-uagb-advanced-heading.uagb-block-ac921c3b.wp-block-uagb-advanced-heading {text-align: left;padding-top: 10px;padding-right: 0px;padding-bottom: 8px;padding-left: 35px;}.wp-block-uagb-advanced-heading.uagb-block-ac921c3b.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 5px;}.wp-block-uagb-advanced-heading.uagb-block-ac921c3b.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ac921c3b.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ac921c3b.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ac921c3b .uagb-heading-text{font-size: 19px;}.wp-block-uagb-advanced-heading.uagb-block-ac921c3b .uagb-desc-text{font-size: 15px;line-height: 1.3em;}.wp-block-uagb-container.uagb-block-11065b68 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-11065b68 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-11065b68 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-11065b68 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-11065b68 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-11065b68{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-11065b68 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1920px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-11065b68{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-color: #dce8f2;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-12fadca9 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-12fadca9 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-12fadca9 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-12fadca9 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-12fadca9 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-12fadca9{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-12fadca9 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1920px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-12fadca9{box-shadow: 0px 0px   #00000070 ;padding-top: 15px;padding-bottom: 15px;padding-left: 15px;padding-right: 15px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-top-left-radius: 10px;border-top-right-radius: 10px;border-bottom-left-radius: 10px;border-bottom-right-radius: 10px;border-color: inherit;background-color: var(--ast-global-color-5);flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.uagb-block-6bde0589 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-6bde0589 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-6bde0589 .uagb-ifb-icon svg{fill: #333;}.uagb-block-6bde0589.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-6bde0589 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-6bde0589 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-6bde0589.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-6bde0589.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-6bde0589 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-6bde0589 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-6bde0589 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-6bde0589 .uagb-infobox .uagb-ifb-image-content img{border-radius: 10px;}.uagb-block-6bde0589.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 10px;}.uagb-block-6bde0589.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 10px;}.uagb-block-6bde0589.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 10px;}.uagb-block-6bde0589.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 10px;}.uagb-block-6bde0589 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-6bde0589 .uagb-ifb-title{font-family: \"Georgia\";text-transform: none;text-decoration: underline;font-weight: 600;font-size: 16px;color: #505050;margin-bottom: 2px;margin-top: 5px;margin-left: 5px;margin-right: 0px;}.uagb-block-6bde0589 .uagb-ifb-desc{font-family: \"Georgia\";font-size: 16px;line-height: 1.5em;color: #505050;margin-bottom: 0px;margin-top: 0px;margin-left: 5px;margin-right: 0px;}.uagb-block-6bde0589 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-6bde0589 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-6bde0589 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-6bde0589 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-6bde0589.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-6bde0589.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-6bde0589 .uagb-infobox__content-wrap{text-align: left;}.uagb-block-6bde0589.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-6bde0589.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-6bde0589.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-6bde0589.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-6bde0589 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-6bde0589.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-6bde0589.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-6bde0589.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-6bde0589.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-6bde0589.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-6bde0589.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-6bde0589.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-6bde0589.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-6bde0589.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-cc259940 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-cc259940 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-cc259940 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-cc259940 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-cc259940 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-cc259940{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-cc259940 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1920px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-cc259940{box-shadow: 0px 0px   #00000070 ;padding-top: 15px;padding-bottom: 15px;padding-left: 15px;padding-right: 15px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-top-left-radius: 10px;border-top-right-radius: 10px;border-bottom-left-radius: 10px;border-bottom-right-radius: 10px;border-color: inherit;background-color: var(--ast-global-color-5);flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.uagb-block-3b0ee87a .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-3b0ee87a .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-3b0ee87a .uagb-ifb-icon svg{fill: #333;}.uagb-block-3b0ee87a.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-3b0ee87a .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-3b0ee87a .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-3b0ee87a.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-3b0ee87a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-3b0ee87a .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-3b0ee87a .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-3b0ee87a .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-3b0ee87a .uagb-infobox .uagb-ifb-image-content img{border-radius: 10px;}.uagb-block-3b0ee87a.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 10px;}.uagb-block-3b0ee87a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 10px;}.uagb-block-3b0ee87a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 10px;}.uagb-block-3b0ee87a.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 10px;}.uagb-block-3b0ee87a .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-3b0ee87a .uagb-ifb-title{font-family: \"Georgia\";text-decoration: underline;font-weight: 600;font-size: 16px;color: #505050;margin-bottom: 2px;margin-top: 5px;margin-left: 5px;margin-right: 0px;}.uagb-block-3b0ee87a .uagb-ifb-desc{font-size: 16px;line-height: 1.5em;color: #505050;margin-bottom: 0px;margin-top: 0px;margin-left: 5px;margin-right: 0px;}.uagb-block-3b0ee87a .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-3b0ee87a .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-3b0ee87a .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-3b0ee87a .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-3b0ee87a.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-3b0ee87a.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-3b0ee87a .uagb-infobox__content-wrap{text-align: left;}.uagb-block-3b0ee87a.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-3b0ee87a.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-3b0ee87a.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-3b0ee87a.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-3b0ee87a .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-3b0ee87a.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-3b0ee87a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-3b0ee87a.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-3b0ee87a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-3b0ee87a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-3b0ee87a.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-3b0ee87a.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-3b0ee87a.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-3b0ee87a.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-0a8f7229 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-0a8f7229 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-0a8f7229 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-0a8f7229 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-0a8f7229 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-0a8f7229{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-0a8f7229{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 5px;padding-left: 5px;padding-right: 5px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-top-left-radius: 10px;border-top-right-radius: 10px;border-bottom-left-radius: 10px;border-bottom-right-radius: 10px;border-color: inherit;background-color: #dce8f2;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-advanced-heading.uagb-block-12d79b7f.wp-block-uagb-advanced-heading .uagb-heading-text{color: #505050;}.wp-block-uagb-advanced-heading.uagb-block-12d79b7f.wp-block-uagb-advanced-heading {text-align: left;padding-top: 10px;padding-right: 0px;padding-bottom: 8px;padding-left: 35px;}.wp-block-uagb-advanced-heading.uagb-block-12d79b7f.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 5px;}.wp-block-uagb-advanced-heading.uagb-block-12d79b7f.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-12d79b7f.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-12d79b7f.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-12d79b7f .uagb-heading-text{font-size: 19px;}.wp-block-uagb-advanced-heading.uagb-block-12d79b7f .uagb-desc-text{font-size: 15px;line-height: 1.3em;}.wp-block-uagb-container.uagb-block-5fd08e28 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5fd08e28 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5fd08e28 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5fd08e28 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5fd08e28 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5fd08e28{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5fd08e28 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1920px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-5fd08e28{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-color: #dce8f2;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-7b0f7102 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-7b0f7102 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-7b0f7102 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-7b0f7102 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-7b0f7102 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7b0f7102{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7b0f7102 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1920px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-7b0f7102{box-shadow: 0px 0px   #00000070 ;padding-top: 15px;padding-bottom: 15px;padding-left: 15px;padding-right: 15px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-top-left-radius: 10px;border-top-right-radius: 10px;border-bottom-left-radius: 10px;border-bottom-right-radius: 10px;border-color: inherit;background-color: var(--ast-global-color-5);flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.uagb-block-9887ffcd .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-9887ffcd .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-9887ffcd .uagb-ifb-icon svg{fill: #333;}.uagb-block-9887ffcd.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-9887ffcd .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-9887ffcd .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-9887ffcd.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-9887ffcd.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-9887ffcd .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-9887ffcd .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-9887ffcd .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-9887ffcd .uagb-infobox .uagb-ifb-image-content img{border-radius: 10px;}.uagb-block-9887ffcd.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 10px;}.uagb-block-9887ffcd.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 10px;}.uagb-block-9887ffcd.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 10px;}.uagb-block-9887ffcd.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 10px;}.uagb-block-9887ffcd .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-9887ffcd .uagb-ifb-title{font-family: \"Georgia\";text-transform: none;text-decoration: underline;font-weight: 600;font-size: 16px;color: #505050;margin-bottom: 2px;margin-top: 5px;margin-left: 5px;margin-right: 0px;}.uagb-block-9887ffcd .uagb-ifb-desc{font-family: \"Georgia\";font-size: 16px;line-height: 1.5em;color: #505050;margin-bottom: 0px;margin-top: 0px;margin-left: 5px;margin-right: 0px;}.uagb-block-9887ffcd .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-9887ffcd .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-9887ffcd .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-9887ffcd .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-9887ffcd.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-9887ffcd.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-9887ffcd .uagb-infobox__content-wrap{text-align: left;}.uagb-block-9887ffcd.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-9887ffcd.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-9887ffcd.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-9887ffcd.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-9887ffcd .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-9887ffcd.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-9887ffcd.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-9887ffcd.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-9887ffcd.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-9887ffcd.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-9887ffcd.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-9887ffcd.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-9887ffcd.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-9887ffcd.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-d14fb2e8 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-d14fb2e8 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-d14fb2e8 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-d14fb2e8 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-d14fb2e8 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-d14fb2e8{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d14fb2e8 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1920px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-d14fb2e8{box-shadow: 0px 0px   #00000070 ;padding-top: 15px;padding-bottom: 15px;padding-left: 15px;padding-right: 15px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-top-left-radius: 10px;border-top-right-radius: 10px;border-bottom-left-radius: 10px;border-bottom-right-radius: 10px;border-color: inherit;background-color: var(--ast-global-color-5);flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.uagb-block-8384c17e .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-8384c17e .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-8384c17e .uagb-ifb-icon svg{fill: #333;}.uagb-block-8384c17e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-8384c17e .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-8384c17e .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-8384c17e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-8384c17e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-8384c17e .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-8384c17e .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-8384c17e .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-8384c17e .uagb-infobox .uagb-ifb-image-content img{border-radius: 10px;}.uagb-block-8384c17e.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 10px;}.uagb-block-8384c17e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 10px;}.uagb-block-8384c17e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 10px;}.uagb-block-8384c17e.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 10px;}.uagb-block-8384c17e .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-8384c17e .uagb-ifb-title{font-family: \"Georgia\";text-decoration: underline;font-weight: 600;font-size: 16px;color: #505050;margin-bottom: 2px;margin-top: 5px;margin-left: 5px;margin-right: 0px;}.uagb-block-8384c17e .uagb-ifb-desc{font-size: 16px;line-height: 1.5em;color: #505050;margin-bottom: 0px;margin-top: 0px;margin-left: 5px;margin-right: 0px;}.uagb-block-8384c17e .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-8384c17e .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-8384c17e .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-8384c17e .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-8384c17e.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-8384c17e.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-8384c17e .uagb-infobox__content-wrap{text-align: left;}.uagb-block-8384c17e.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-8384c17e.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-8384c17e.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-8384c17e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-8384c17e .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-8384c17e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-8384c17e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-8384c17e.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-8384c17e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-8384c17e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-8384c17e.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-8384c17e.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-8384c17e.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-8384c17e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-cb123a13 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-cb123a13 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-cb123a13 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-cb123a13 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-cb123a13 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-cb123a13{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-cb123a13{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 5px;padding-left: 5px;padding-right: 5px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-top-left-radius: 10px;border-top-right-radius: 10px;border-bottom-left-radius: 10px;border-bottom-right-radius: 10px;border-color: inherit;background-color: #dce8f2;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-advanced-heading.uagb-block-8e29bb04.wp-block-uagb-advanced-heading .uagb-heading-text{color: #505050;}.wp-block-uagb-advanced-heading.uagb-block-8e29bb04.wp-block-uagb-advanced-heading {text-align: left;padding-top: 10px;padding-right: 0px;padding-bottom: 8px;padding-left: 35px;}.wp-block-uagb-advanced-heading.uagb-block-8e29bb04.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 5px;}.wp-block-uagb-advanced-heading.uagb-block-8e29bb04.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-8e29bb04.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-8e29bb04.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-8e29bb04 .uagb-heading-text{font-size: 19px;}.wp-block-uagb-advanced-heading.uagb-block-8e29bb04 .uagb-desc-text{font-size: 15px;line-height: 1.3em;}.wp-block-uagb-container.uagb-block-fd6bb0ed .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-fd6bb0ed .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-fd6bb0ed .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-fd6bb0ed .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-fd6bb0ed .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-fd6bb0ed{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-fd6bb0ed > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1920px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-fd6bb0ed{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-color: #dce8f2;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-bc3c1c67 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-bc3c1c67 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-bc3c1c67 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-bc3c1c67 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-bc3c1c67 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-bc3c1c67{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-bc3c1c67 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1920px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-bc3c1c67{box-shadow: 0px 0px   #00000070 ;padding-top: 15px;padding-bottom: 15px;padding-left: 15px;padding-right: 15px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-top-left-radius: 10px;border-top-right-radius: 10px;border-bottom-left-radius: 10px;border-bottom-right-radius: 10px;border-color: inherit;background-color: var(--ast-global-color-5);flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.uagb-block-72883329 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-72883329 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-72883329 .uagb-ifb-icon svg{fill: #333;}.uagb-block-72883329.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-72883329 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-72883329 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-72883329.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-72883329.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-72883329 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-72883329 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-72883329 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-72883329 .uagb-infobox .uagb-ifb-image-content img{border-radius: 10px;}.uagb-block-72883329.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 10px;}.uagb-block-72883329.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 10px;}.uagb-block-72883329.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 10px;}.uagb-block-72883329.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 10px;}.uagb-block-72883329 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-72883329 .uagb-ifb-title{font-family: \"Georgia\";text-transform: none;text-decoration: underline;font-weight: 600;font-size: 16px;color: #505050;margin-bottom: 2px;margin-top: 5px;margin-left: 5px;margin-right: 0px;}.uagb-block-72883329 .uagb-ifb-desc{font-family: \"Georgia\";font-size: 16px;line-height: 1.5em;color: #505050;margin-bottom: 0px;margin-top: 0px;margin-left: 5px;margin-right: 0px;}.uagb-block-72883329 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-72883329 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-72883329 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-72883329 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-72883329.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-72883329.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-72883329 .uagb-infobox__content-wrap{text-align: left;}.uagb-block-72883329.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-72883329.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-72883329.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-72883329.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-72883329 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-72883329.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-72883329.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-72883329.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-72883329.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-72883329.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-72883329.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-72883329.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-72883329.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-72883329.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-80ff24bb .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-80ff24bb .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-80ff24bb .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-80ff24bb .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-80ff24bb .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-80ff24bb{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-80ff24bb > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1920px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-80ff24bb{box-shadow: 0px 0px   #00000070 ;padding-top: 15px;padding-bottom: 15px;padding-left: 15px;padding-right: 15px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-top-left-radius: 10px;border-top-right-radius: 10px;border-bottom-left-radius: 10px;border-bottom-right-radius: 10px;border-color: inherit;background-color: var(--ast-global-color-5);flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.uagb-block-97d9f7dc .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-97d9f7dc .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-97d9f7dc .uagb-ifb-icon svg{fill: #333;}.uagb-block-97d9f7dc.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-97d9f7dc .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-97d9f7dc .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-97d9f7dc.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-97d9f7dc.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-97d9f7dc .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-97d9f7dc .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-97d9f7dc .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-97d9f7dc .uagb-infobox .uagb-ifb-image-content img{border-radius: 10px;}.uagb-block-97d9f7dc.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 10px;}.uagb-block-97d9f7dc.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 10px;}.uagb-block-97d9f7dc.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 10px;}.uagb-block-97d9f7dc.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 10px;}.uagb-block-97d9f7dc .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-97d9f7dc .uagb-ifb-title{font-family: \"Georgia\";text-decoration: underline;font-weight: 600;font-size: 16px;color: #505050;margin-bottom: 2px;margin-top: 5px;margin-left: 5px;margin-right: 0px;}.uagb-block-97d9f7dc .uagb-ifb-desc{font-size: 16px;line-height: 1.5em;color: #505050;margin-bottom: 0px;margin-top: 0px;margin-left: 5px;margin-right: 0px;}.uagb-block-97d9f7dc .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-97d9f7dc .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-97d9f7dc .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-97d9f7dc .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-97d9f7dc.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-97d9f7dc.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-97d9f7dc .uagb-infobox__content-wrap{text-align: left;}.uagb-block-97d9f7dc.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-97d9f7dc.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-97d9f7dc.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-97d9f7dc.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-97d9f7dc .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-97d9f7dc.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-97d9f7dc.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-97d9f7dc.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-97d9f7dc.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-97d9f7dc.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-97d9f7dc.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-97d9f7dc.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-97d9f7dc.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-97d9f7dc.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-ac83c8c5 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ac83c8c5 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ac83c8c5 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ac83c8c5 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ac83c8c5 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ac83c8c5{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-ac83c8c5{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 5px;padding-left: 5px;padding-right: 5px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-top-left-radius: 10px;border-top-right-radius: 10px;border-bottom-left-radius: 10px;border-bottom-right-radius: 10px;border-color: inherit;background-color: #dce8f2;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-advanced-heading.uagb-block-2f290585.wp-block-uagb-advanced-heading .uagb-heading-text{color: #505050;}.wp-block-uagb-advanced-heading.uagb-block-2f290585.wp-block-uagb-advanced-heading {text-align: left;padding-top: 10px;padding-right: 0px;padding-bottom: 8px;padding-left: 35px;}.wp-block-uagb-advanced-heading.uagb-block-2f290585.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 5px;}.wp-block-uagb-advanced-heading.uagb-block-2f290585.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-2f290585.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-2f290585.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-2f290585 .uagb-heading-text{font-size: 19px;}.wp-block-uagb-advanced-heading.uagb-block-2f290585 .uagb-desc-text{font-size: 15px;line-height: 1.3em;}.wp-block-uagb-container.uagb-block-b1d72dc5 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-b1d72dc5 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-b1d72dc5 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-b1d72dc5 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-b1d72dc5 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b1d72dc5{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b1d72dc5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1920px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-b1d72dc5{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-color: #dce8f2;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-9e622077 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-9e622077 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-9e622077 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-9e622077 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-9e622077 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9e622077{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9e622077 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1920px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-9e622077{box-shadow: 0px 0px   #00000070 ;padding-top: 15px;padding-bottom: 15px;padding-left: 15px;padding-right: 15px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-top-left-radius: 10px;border-top-right-radius: 10px;border-bottom-left-radius: 10px;border-bottom-right-radius: 10px;border-color: inherit;background-color: var(--ast-global-color-5);flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.uagb-block-d0e7e77c .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-d0e7e77c .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-d0e7e77c .uagb-ifb-icon svg{fill: #333;}.uagb-block-d0e7e77c.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-d0e7e77c .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-d0e7e77c .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-d0e7e77c.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-d0e7e77c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-d0e7e77c .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-d0e7e77c .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-d0e7e77c .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-d0e7e77c .uagb-infobox .uagb-ifb-image-content img{border-radius: 10px;}.uagb-block-d0e7e77c.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 10px;}.uagb-block-d0e7e77c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 10px;}.uagb-block-d0e7e77c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 10px;}.uagb-block-d0e7e77c.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 10px;}.uagb-block-d0e7e77c .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-d0e7e77c .uagb-ifb-title{font-family: \"Georgia\";text-transform: none;text-decoration: underline;font-weight: 600;font-size: 16px;color: #505050;margin-bottom: 2px;margin-top: 5px;margin-left: 5px;margin-right: 0px;}.uagb-block-d0e7e77c .uagb-ifb-desc{font-family: \"Georgia\";font-size: 16px;line-height: 1.5em;color: #505050;margin-bottom: 0px;margin-top: 0px;margin-left: 5px;margin-right: 0px;}.uagb-block-d0e7e77c .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-d0e7e77c .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-d0e7e77c .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-d0e7e77c .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-d0e7e77c.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-d0e7e77c.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-d0e7e77c .uagb-infobox__content-wrap{text-align: left;}.uagb-block-d0e7e77c.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-d0e7e77c.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-d0e7e77c.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-d0e7e77c.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-d0e7e77c .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d0e7e77c.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d0e7e77c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d0e7e77c.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d0e7e77c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d0e7e77c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d0e7e77c.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d0e7e77c.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-d0e7e77c.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-d0e7e77c.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-5a5434b8 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5a5434b8 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5a5434b8 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5a5434b8 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5a5434b8 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5a5434b8{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5a5434b8 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1920px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-5a5434b8{box-shadow: 0px 0px   #00000070 ;padding-top: 15px;padding-bottom: 15px;padding-left: 15px;padding-right: 15px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-top-left-radius: 10px;border-top-right-radius: 10px;border-bottom-left-radius: 10px;border-bottom-right-radius: 10px;border-color: inherit;background-color: var(--ast-global-color-5);flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.uagb-block-a23805b1 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-a23805b1 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-a23805b1 .uagb-ifb-icon svg{fill: #333;}.uagb-block-a23805b1.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-a23805b1 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-a23805b1 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-a23805b1.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-a23805b1.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-a23805b1 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-a23805b1 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-a23805b1 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-a23805b1 .uagb-infobox .uagb-ifb-image-content img{border-radius: 10px;}.uagb-block-a23805b1.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 10px;}.uagb-block-a23805b1.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 10px;}.uagb-block-a23805b1.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 10px;}.uagb-block-a23805b1.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 10px;}.uagb-block-a23805b1 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-a23805b1 .uagb-ifb-title{font-family: \"Georgia\";text-decoration: underline;font-weight: 600;font-size: 16px;color: #505050;margin-bottom: 2px;margin-top: 5px;margin-left: 5px;margin-right: 0px;}.uagb-block-a23805b1 .uagb-ifb-desc{font-size: 16px;line-height: 1.5em;color: #505050;margin-bottom: 0px;margin-top: 0px;margin-left: 5px;margin-right: 0px;}.uagb-block-a23805b1 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-a23805b1 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-a23805b1 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-a23805b1 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-a23805b1.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-a23805b1.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-a23805b1 .uagb-infobox__content-wrap{text-align: left;}.uagb-block-a23805b1.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-a23805b1.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-a23805b1.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-a23805b1.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-a23805b1 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-a23805b1.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-a23805b1.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-a23805b1.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-a23805b1.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-a23805b1.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-a23805b1.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-a23805b1.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-a23805b1.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-a23805b1.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}@media only screen and (max-width: 976px) {.uagb-block-be2cc2f9 .uagb-toc__wrap{border-style: solid;}.uagb-block-be2cc2f9 .uagb-toc__list-wrap{column-count: 1;overflow: hidden;text-align: left;}.uagb-block-be2cc2f9 .uagb-toc__list-wrap > ul.uagb-toc__list > li:first-child{padding-top: 0;}.uagb-block-be2cc2f9 .uagb-toc__list-wrap ul.uagb-toc__list:last-child > li:last-child{padding-bottom: 0;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e064fb7f{width: 100%;}.wp-block-uagb-container.uagb-block-e064fb7f{padding-top: 10px;padding-bottom: 5px;padding-left: 5px;padding-right: 5px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #dce8f2;}.wp-block-uagb-advanced-heading.uagb-block-ac921c3b.wp-block-uagb-advanced-heading {margin-bottom: 10px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-11065b68{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-11065b68 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-11065b68{padding-top: 0px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #dce8f2;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-12fadca9{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-12fadca9 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-12fadca9{padding-top: 15px;padding-bottom: 15px;padding-left: 15px;padding-right: 15px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: var(--ast-global-color-5);}.uagb-block-6bde0589.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-6bde0589.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-6bde0589.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-6bde0589 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-6bde0589 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-6bde0589 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-6bde0589 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-6bde0589 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-6bde0589.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-6bde0589.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-6bde0589.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-6bde0589.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-cc259940{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-cc259940 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-cc259940{padding-top: 15px;padding-bottom: 15px;padding-left: 15px;padding-right: 15px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: var(--ast-global-color-5);}.uagb-block-3b0ee87a.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-3b0ee87a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-3b0ee87a.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-3b0ee87a .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-3b0ee87a .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-3b0ee87a .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-3b0ee87a .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-3b0ee87a .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-3b0ee87a.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-3b0ee87a.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-3b0ee87a.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-3b0ee87a.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-0a8f7229{width: 100%;}.wp-block-uagb-container.uagb-block-0a8f7229{padding-top: 10px;padding-bottom: 5px;padding-left: 5px;padding-right: 5px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #dce8f2;}.wp-block-uagb-advanced-heading.uagb-block-12d79b7f.wp-block-uagb-advanced-heading {margin-bottom: 10px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5fd08e28{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5fd08e28 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-5fd08e28{padding-top: 0px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #dce8f2;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7b0f7102{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7b0f7102 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-7b0f7102{padding-top: 15px;padding-bottom: 15px;padding-left: 15px;padding-right: 15px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: var(--ast-global-color-5);}.uagb-block-9887ffcd.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-9887ffcd.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-9887ffcd.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-9887ffcd .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-9887ffcd .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-9887ffcd .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-9887ffcd .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-9887ffcd .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-9887ffcd.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-9887ffcd.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-9887ffcd.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-9887ffcd.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-d14fb2e8{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d14fb2e8 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-d14fb2e8{padding-top: 15px;padding-bottom: 15px;padding-left: 15px;padding-right: 15px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: var(--ast-global-color-5);}.uagb-block-8384c17e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-8384c17e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-8384c17e.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-8384c17e .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-8384c17e .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-8384c17e .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-8384c17e .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-8384c17e .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-8384c17e.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-8384c17e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-8384c17e.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-8384c17e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-cb123a13{width: 100%;}.wp-block-uagb-container.uagb-block-cb123a13{padding-top: 10px;padding-bottom: 5px;padding-left: 5px;padding-right: 5px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #dce8f2;}.wp-block-uagb-advanced-heading.uagb-block-8e29bb04.wp-block-uagb-advanced-heading {margin-bottom: 10px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-fd6bb0ed{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-fd6bb0ed > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-fd6bb0ed{padding-top: 0px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #dce8f2;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-bc3c1c67{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-bc3c1c67 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-bc3c1c67{padding-top: 15px;padding-bottom: 15px;padding-left: 15px;padding-right: 15px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: var(--ast-global-color-5);}.uagb-block-72883329.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-72883329.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-72883329.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-72883329 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-72883329 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-72883329 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-72883329 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-72883329 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-72883329.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-72883329.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-72883329.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-72883329.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-80ff24bb{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-80ff24bb > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-80ff24bb{padding-top: 15px;padding-bottom: 15px;padding-left: 15px;padding-right: 15px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: var(--ast-global-color-5);}.uagb-block-97d9f7dc.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-97d9f7dc.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-97d9f7dc.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-97d9f7dc .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-97d9f7dc .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-97d9f7dc .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-97d9f7dc .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-97d9f7dc .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-97d9f7dc.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-97d9f7dc.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-97d9f7dc.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-97d9f7dc.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ac83c8c5{width: 100%;}.wp-block-uagb-container.uagb-block-ac83c8c5{padding-top: 10px;padding-bottom: 5px;padding-left: 5px;padding-right: 5px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #dce8f2;}.wp-block-uagb-advanced-heading.uagb-block-2f290585.wp-block-uagb-advanced-heading {margin-bottom: 10px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b1d72dc5{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b1d72dc5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-b1d72dc5{padding-top: 0px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #dce8f2;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9e622077{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9e622077 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-9e622077{padding-top: 15px;padding-bottom: 15px;padding-left: 15px;padding-right: 15px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: var(--ast-global-color-5);}.uagb-block-d0e7e77c.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-d0e7e77c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-d0e7e77c.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-d0e7e77c .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-d0e7e77c .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-d0e7e77c .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-d0e7e77c .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-d0e7e77c .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-d0e7e77c.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-d0e7e77c.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-d0e7e77c.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-d0e7e77c.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5a5434b8{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5a5434b8 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-5a5434b8{padding-top: 15px;padding-bottom: 15px;padding-left: 15px;padding-right: 15px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: var(--ast-global-color-5);}.uagb-block-a23805b1.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-a23805b1.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-a23805b1.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-a23805b1 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-a23805b1 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-a23805b1 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-a23805b1 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-a23805b1 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-a23805b1.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-a23805b1.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-a23805b1.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-a23805b1.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}@media only screen and (max-width: 767px) {.uagb-block-be2cc2f9 .uagb-toc__wrap{border-style: solid;}.uagb-block-be2cc2f9 .uagb-toc__list-wrap{column-count: 1;overflow: hidden;text-align: left;}.uagb-block-be2cc2f9 .uagb-toc__list-wrap > ul.uagb-toc__list > li:first-child{padding-top: 0;}.uagb-block-be2cc2f9 .uagb-toc__list-wrap ul.uagb-toc__list:last-child > li:last-child{padding-bottom: 0;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e064fb7f{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-e064fb7f{padding-top: 10px;padding-bottom: 5px;padding-left: 5px;padding-right: 5px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #dce8f2;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-11065b68{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-11065b68 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-11065b68{padding-top: 0px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #dce8f2;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-12fadca9{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-12fadca9 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-12fadca9{padding-top: 15px;padding-bottom: 15px;padding-left: 15px;padding-right: 15px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: var(--ast-global-color-5);flex-wrap: wrap;}.uagb-block-6bde0589.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-6bde0589.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-6bde0589 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-6bde0589 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-6bde0589.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-6bde0589 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-6bde0589 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-6bde0589 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-6bde0589.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-6bde0589.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-6bde0589.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-6bde0589.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-cc259940{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-cc259940 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-cc259940{padding-top: 15px;padding-bottom: 15px;padding-left: 15px;padding-right: 15px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: var(--ast-global-color-5);flex-wrap: wrap;}.uagb-block-3b0ee87a.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-3b0ee87a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-3b0ee87a .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-3b0ee87a .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-3b0ee87a.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-3b0ee87a .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-3b0ee87a .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-3b0ee87a .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-3b0ee87a.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-3b0ee87a.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-3b0ee87a.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-3b0ee87a.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-0a8f7229{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-0a8f7229{padding-top: 10px;padding-bottom: 5px;padding-left: 5px;padding-right: 5px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #dce8f2;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5fd08e28{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5fd08e28 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-5fd08e28{padding-top: 0px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #dce8f2;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7b0f7102{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7b0f7102 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-7b0f7102{padding-top: 15px;padding-bottom: 15px;padding-left: 15px;padding-right: 15px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: var(--ast-global-color-5);flex-wrap: wrap;}.uagb-block-9887ffcd.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-9887ffcd.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-9887ffcd .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-9887ffcd .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-9887ffcd.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-9887ffcd .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-9887ffcd .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-9887ffcd .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-9887ffcd.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-9887ffcd.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-9887ffcd.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-9887ffcd.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-d14fb2e8{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d14fb2e8 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-d14fb2e8{padding-top: 15px;padding-bottom: 15px;padding-left: 15px;padding-right: 15px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: var(--ast-global-color-5);flex-wrap: wrap;}.uagb-block-8384c17e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-8384c17e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-8384c17e .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-8384c17e .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-8384c17e.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-8384c17e .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-8384c17e .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-8384c17e .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-8384c17e.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-8384c17e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-8384c17e.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-8384c17e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-cb123a13{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-cb123a13{padding-top: 10px;padding-bottom: 5px;padding-left: 5px;padding-right: 5px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #dce8f2;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-fd6bb0ed{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-fd6bb0ed > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-fd6bb0ed{padding-top: 0px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #dce8f2;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-bc3c1c67{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-bc3c1c67 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-bc3c1c67{padding-top: 15px;padding-bottom: 15px;padding-left: 15px;padding-right: 15px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: var(--ast-global-color-5);flex-wrap: wrap;}.uagb-block-72883329.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-72883329.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-72883329 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-72883329 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-72883329.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-72883329 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-72883329 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-72883329 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-72883329.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-72883329.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-72883329.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-72883329.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-80ff24bb{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-80ff24bb > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-80ff24bb{padding-top: 15px;padding-bottom: 15px;padding-left: 15px;padding-right: 15px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: var(--ast-global-color-5);flex-wrap: wrap;}.uagb-block-97d9f7dc.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-97d9f7dc.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-97d9f7dc .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-97d9f7dc .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-97d9f7dc.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-97d9f7dc .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-97d9f7dc .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-97d9f7dc .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-97d9f7dc.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-97d9f7dc.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-97d9f7dc.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-97d9f7dc.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ac83c8c5{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-ac83c8c5{padding-top: 10px;padding-bottom: 5px;padding-left: 5px;padding-right: 5px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #dce8f2;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b1d72dc5{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b1d72dc5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-b1d72dc5{padding-top: 0px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #dce8f2;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9e622077{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9e622077 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-9e622077{padding-top: 15px;padding-bottom: 15px;padding-left: 15px;padding-right: 15px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: var(--ast-global-color-5);flex-wrap: wrap;}.uagb-block-d0e7e77c.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-d0e7e77c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-d0e7e77c .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-d0e7e77c .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-d0e7e77c.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-d0e7e77c .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-d0e7e77c .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-d0e7e77c .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-d0e7e77c.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-d0e7e77c.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-d0e7e77c.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-d0e7e77c.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5a5434b8{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5a5434b8 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-5a5434b8{padding-top: 15px;padding-bottom: 15px;padding-left: 15px;padding-right: 15px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: var(--ast-global-color-5);flex-wrap: wrap;}.uagb-block-a23805b1.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-a23805b1.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-a23805b1 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-a23805b1 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-a23805b1.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-a23805b1 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-a23805b1 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-a23805b1 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-a23805b1.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-a23805b1.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-a23805b1.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-a23805b1.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}\";s:2:\"js\";s:384:\"document.addEventListener(\"DOMContentLoaded\", function(){ window.addEventListener( 'load', function(){\n\tUAGBTableOfContents._run( {\"mappingHeaders\":[true,true,true,false,false,false],\"scrollToTop\":false,\"makeCollapsible\":true,\"enableCollapsableList\":false,\"initialCollapse\":true,\"markerView\":\"disc\",\"isFrontend\":true,\"initiallyCollapseList\":false}, '.uagb-block-be2cc2f9' );\n} );\n });\";s:18:\"current_block_list\";a:11:{i:0;s:14:\"core\/paragraph\";i:1;s:22:\"uagb\/table-of-contents\";i:2;s:12:\"core\/heading\";i:3;s:10:\"core\/image\";i:4;s:14:\"uagb\/container\";i:5;s:21:\"uagb\/advanced-heading\";i:8;s:13:\"uagb\/info-box\";i:9;s:11:\"core\/spacer\";i:10;s:9:\"core\/list\";i:11;s:14:\"core\/list-item\";i:12;s:15:\"yoast\/faq-block\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";i:1788336927;s:6:\"gfonts\";a:1:{s:7:\"Default\";a:2:{s:10:\"fontfamily\";s:7:\"Default\";s:12:\"fontvariants\";a:0:{}}}s:10:\"gfonts_url\";s:77:\"https:\/\/fonts.googleapis.com\/css?family=Default&subset=latin&display=fallback\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":["https:\/\/smilingway.cz\/wp-content\/uploads\/2022\/08\/lago-di-como-hlavni-2.jpg",1500,844,false],"thumbnail":["https:\/\/smilingway.cz\/wp-content\/uploads\/2022\/08\/lago-di-como-hlavni-2-150x150.jpg",150,150,true],"medium":["https:\/\/smilingway.cz\/wp-content\/uploads\/2022\/08\/lago-di-como-hlavni-2-300x169.jpg",300,169,true],"medium_large":["https:\/\/smilingway.cz\/wp-content\/uploads\/2022\/08\/lago-di-como-hlavni-2-768x432.jpg",768,432,true],"large":["https:\/\/smilingway.cz\/wp-content\/uploads\/2022\/08\/lago-di-como-hlavni-2-1024x576.jpg",1024,576,true],"1536x1536":["https:\/\/smilingway.cz\/wp-content\/uploads\/2022\/08\/lago-di-como-hlavni-2.jpg",1500,844,false],"2048x2048":["https:\/\/smilingway.cz\/wp-content\/uploads\/2022\/08\/lago-di-como-hlavni-2.jpg",1500,844,false]},"uagb_author_info":{"display_name":"Blanka","author_link":"https:\/\/smilingway.cz\/de\/author\/admin\/"},"uagb_comment_info":0,"uagb_excerpt":"Der Lago di Como ist einer der sch\u00f6nsten Seen Italiens. Ber\u00fchmtheiten wie George Clooney, Giovanni Versace, Lionel Messi und Madonna haben sich hier niedergelassen. Der [&hellip;]","_links":{"self":[{"href":"https:\/\/smilingway.cz\/de\/wp-json\/wp\/v2\/posts\/129637","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smilingway.cz\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smilingway.cz\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smilingway.cz\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smilingway.cz\/de\/wp-json\/wp\/v2\/comments?post=129637"}],"version-history":[{"count":0,"href":"https:\/\/smilingway.cz\/de\/wp-json\/wp\/v2\/posts\/129637\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smilingway.cz\/de\/wp-json\/wp\/v2\/media\/98130"}],"wp:attachment":[{"href":"https:\/\/smilingway.cz\/de\/wp-json\/wp\/v2\/media?parent=129637"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smilingway.cz\/de\/wp-json\/wp\/v2\/categories?post=129637"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smilingway.cz\/de\/wp-json\/wp\/v2\/tags?post=129637"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}